{"id":677,"date":"2013-02-14T19:41:13","date_gmt":"2013-02-14T18:41:13","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=677"},"modified":"2013-02-14T19:41:13","modified_gmt":"2013-02-14T18:41:13","slug":"la-renuncia","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/02\/14\/la-renuncia\/","title":{"rendered":"La renuncia"},"content":{"rendered":"<p><strong><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/02\/ratzinger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-678\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/02\/ratzinger.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Joseph Ratzinger<\/strong> ha entendido y aceptado que su ciclo ha terminado, que no puede realizar la funci\u00f3n para la que fue elegido con la hondura que considera necesaria. O bien lo \u00fanico que le pide al acto final de su vida, como el poeta <strong>Caballero Bonald,<\/strong> sea mantener lo que le queda de salud y un poco de silencio, y emplear una y otro en tocar a <strong>Mozart<\/strong>. O bien las intrigas vaticanas han terminado hasti\u00e1ndolo. \u00bfMotivos? Casi seguro sean una conjunci\u00f3n de estos y algunos m\u00e1s, probablemente nunca lleguemos a conocerlos todos. Pero en el fondo qu\u00e9 importan los motivos. Ante una decisi\u00f3n as\u00ed lo \u00fanico que cuenta es la voluntad de llevarla a cabo, y en una sociedad donde la renuncia es sin\u00f3nimo de rendici\u00f3n \u2014y rendici\u00f3n sin\u00f3nimo de falta de car\u00e1cter y ego\u00edsmo\u2014, la decisi\u00f3n de Ratzinger va a suponerle el repudio de una gran parte no ya de los fieles, que se sentir\u00e1n <<traicionados>> y ofendidos personalmente porque el ex Sumo no se ha resignado con fatalismo cat\u00f3lico a aceptar las cosas como vienen, sino de quienes hasta ahora le han criticado sencillamente por ocupar el puesto que ocupaba. Sin embargo renunciar en la c\u00faspide es una acci\u00f3n que solo los m\u00e1s grandes son capaces de llevar a cabo, un acto de afirmaci\u00f3n de la identidad personal heroico, y si vivi\u00e9ramos en una sociedad en la que realmente el individuo fuera el centro moral desde el que construir el ordenamiento jur\u00eddico, en la que la libertad fuera en verdad un atributo inherente al hombre y no una palabra que pegar en carteles electorales, nadie cuestionar\u00eda el movimiento de retiro de Ratzinger. Comp\u00e1rese este movimiento con el estatismo de quienes, pese a las evidencias vergonzantes que los se\u00f1alan, se niegan a abandonar el esca\u00f1o o el sill\u00f3n del Consejo de Administraci\u00f3n de turno hasta que los destituyen o la setencia es finalmente firme, despu\u00e9s de a\u00f1os y a\u00f1os. Ratzinger, por contra, ha realizado quiz\u00e1 el acto pol\u00edtico m\u00e1s subversivo y noble de lo que llevamos de d\u00e9cada.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 14\/2\/2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joseph Ratzinger ha entendido y aceptado que su ciclo ha terminado, que no puede realizar la funci\u00f3n para la que fue elegido con la hondura que considera necesaria. O bien lo \u00fanico que le pide al acto final de su vida, como el poeta Caballero Bonald, sea mantener lo que le queda de salud y [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[232,529,600,749,766,768,839],"class_list":["post-677","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-deber","tag-libertad","tag-moral","tag-ratzinger","tag-religion","tag-renuncia","tag-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=677"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/677\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}