{"id":726,"date":"2013-05-17T17:54:07","date_gmt":"2013-05-17T15:54:07","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=726"},"modified":"2013-05-17T17:54:07","modified_gmt":"2013-05-17T15:54:07","slug":"lo-de-toledo","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/05\/17\/lo-de-toledo\/","title":{"rendered":"Lo de Toledo"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/05\/willy_toledo_0-e1368805955780.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-727\" title=\"willy_toledo_0\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/05\/willy_toledo_0-e1368805955780.jpg\" alt=\"\" width=\"120\" height=\"180\" \/><\/a>El anuncio del actor <strong>Guillermo Toledo<\/strong> de que permuta Espa\u00f1a por Cuba como lugar de residencia ha polarizado a la opini\u00f3n p\u00fablica de una manera fan\u00e1tica, obvi\u00e1ndose con frecuencia el hecho central de que, m\u00e1s all\u00e1 de los motivos que lo han llevado a largarse, Toledo puede largarse y muchos que quisieran \u2015destino aparte\u2015 no pueden. Lo cual lo convierte ya en un privilegiado. Quiz\u00e1 hubiera sido m\u00e1s elegante largarse sin m\u00e1s y dejar que la opini\u00f3n p\u00fablica fantasease con los motivos exactos, pero desde el momento en que es \u00e9l quien los hace p\u00fablicos, est\u00e1 encendiendo la mecha de los comentarios, como muy bien era consciente; si no buscaba el ruido y la furia desde luego ruido y furia no le han pillado por sorpresa; m\u00e1s aun: incluso lo justifican ante quienes suscriben los motivos de su marcha: <<\u00bfC\u00f3mo no va a marcharse, con lo que le odian?>> Tampoco es accidental el elegir el marco de la televisi\u00f3n chavista para hacer el anuncio: el efecto ha sido exponencial, mucho mayor que si hubiera dado la entrevista en Espa\u00f1a, donde los tuits como aguijones de los espectadores hubieran sin duda modificado el curso de las preguntas, aun pactadas.<\/p>\n<p>Es evidente que <<nuestro sistema>>, como lo define Toledo, es m\u00e1s que perfectible y demanda mecanismos correctores urgentes, pero desde luego tambi\u00e9n lo es ese chavismo\/castrismo que \u00e9l importar\u00eda tal cual a Espa\u00f1a. En la Espa\u00f1a de los suicidios al menos se le permite decir muy alto que su primer representante \u2015elegido por el pueblo\u2015 tiene un sustrato dictatorial, sea o no cierto. Que lo intente en La Habana cuando llegue.<\/p>\n<p>Guillermo Toledo comenz\u00f3 cubaniz\u00e1ndose el nombre art\u00edstico y poco a poco se le ha cubanizado el juicio. En el fondo uno lo ve como un so\u00f1ador. Willy Toledo sue\u00f1a con una utop\u00eda pero de utop\u00edas fracasadas est\u00e1 la Historia llena. Por si nadie se lo ha dicho, en Cuba tambi\u00e9n hay clases.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 16\/5\/2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El anuncio del actor Guillermo Toledo de que permuta Espa\u00f1a por Cuba como lugar de residencia ha polarizado a la opini\u00f3n p\u00fablica de una manera fan\u00e1tica, obvi\u00e1ndose con frecuencia el hecho central de que, m\u00e1s all\u00e1 de los motivos que lo han llevado a largarse, Toledo puede largarse y muchos que quisieran \u2015destino aparte\u2015 no [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[219,305,415,433,529,839,953],"class_list":["post-726","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-cuba","tag-espana","tag-historia","tag-igualdad","tag-libertad","tag-sociedad","tag-willy-toledo"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/726\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}