{"id":767,"date":"2013-09-21T23:42:04","date_gmt":"2013-09-21T21:42:04","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=767"},"modified":"2013-09-21T23:42:04","modified_gmt":"2013-09-21T21:42:04","slug":"la-voz-de-robinson","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/09\/21\/la-voz-de-robinson\/","title":{"rendered":"La voz de Robinson"},"content":{"rendered":"<p>No necesit\u00f3 el lector atento m\u00e1s que una novela \u2015<em>Beatus ille<\/em>, 1986\u2015 para darse cuenta de que se encontraba ante un autor que respiraba a su propio aire, con una propuesta narrativa que se separaba de las tendecias mayoritarias del momento \u2015garc\u00edamarquismo, minimalismo airado\u2015 con tanta discreci\u00f3n como voluntad. Aquella primera novela y la compilaci\u00f3n de art\u00edculos que la precedieron mostraban ya en gran medida los rasgos que iban a informar la obra de <strong>Mu\u00f1oz Molina<\/strong>, cuyo impulso b\u00e1sico es una aproximaci\u00f3n moral al hecho literario en el sentido m\u00e1s inmediato, material, de la escritura como objeto del acto de escribir, y en el mediato de la escritura como herramienta para la exploraci\u00f3n de la realidad. Impulso doble que en el fondo es uno, o al menos debe ser uno; el texto por el texto se termina agotando, est\u00e9ril, en s\u00ed mismo, y la exploraci\u00f3n de la realidad por la escritura sin prestar atenci\u00f3n al hecho de escribir supone una contradicci\u00f3n que da como resultado unos frutos pobr\u00edsimos, planos, evidentes, que podr\u00edan haberse obtenido igual con un vistazo superficial de entrada y as\u00ed al menos ahorrado tiempo. No es accidental que en la obra de Mu\u00f1oz Molina la idea de isla, ya desde la compilaci\u00f3n aludida, sea una presencia constante; la realidad es esa isla y el escritor el n\u00e1ufrago que con curiosidad y cuidado la explora, pese a saber que el misterio de la isla no terminar\u00e1 nunca de revel\u00e1rsele del todo, lo cual no ha de ser \u00f3bice sino acicate para recorrerla.<\/p>\n<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/09\/antoniomunozmolina-e1379799672481.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-769\" title=\"antoniomunozmolina\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/09\/antoniomunozmolina-e1379799672481.jpg\" alt=\"\" width=\"200\" height=\"122\" \/><\/a>La realidad por tanto como isla inagotable, solo que algunos escritores prefieren acotarse a un \u00e1rea restringida, confortable de la isla e ignorar otros territorios o limitarse a tolerarlos con desd\u00e9n educado, sea el territorio pol\u00edtico, sea el cient\u00edfico, sea el de las otras ramas del arte.\u00a0 El impulso moral que mueve a Mu\u00f1oz Molina le lleva en cambio a internarse en ellos, tambi\u00e9n en los que tradicionalmente se han considerado menores, como la fotograf\u00eda o el jazz, con la curiosidad y la modestia del explorador que sabe que la mayor recompensa de la b\u00fasqueda est\u00e1 en la b\u00fasqueda misma. Es incluso \u2015hecho casi in\u00e9dito en el intelectual patrio\u2015 capaz sencillamente de admitir sus ignorancias, aunque las ignorancias de MM sean escasas y cada vez menores. (Ejemplo \u00faltimo de esta curiosidad aut\u00f3noma y sin linderos es el di\u00e1logo que mantendr\u00e1 en el Hay Festival sobre <strong>Wagner<\/strong> y <strong>Verdi<\/strong> y que lleva por t\u00edtulo <em>Traducir la m\u00fasica<\/em>. Inicialmente podemos pensar que si hay una materia intraducible, y en la que el intento de traducirla resulte m\u00e1s in\u00fatil, es la m\u00fasica; pero eso: inicialmente. Qui\u00e9n sabe lo que la exploraci\u00f3n puede deparar.)<\/p>\n<p>En lo que se refiere a la herramienta con la que explorar la isla, si hay algo por lo que se preocupe Mu\u00f1oz Molina es por no dejar de afinarla. Dentro inevitablemente de su registro \u2015al fin y al cabo, cada cual tiene un timbre particular, desde <strong>Mozart<\/strong> a <strong>Faulkner<\/strong>\u2015, la voz de MM no ha cedido a la tentaci\u00f3n de abandonarse al solipsismo y sigue buscando las maneras m\u00e1s eficaces de comunicar las visiones parciales que de la isla se va formando. Y es que el estilo del escritor no es una cuesti\u00f3n de redactar m\u00e1s o menos pulcramente o de escribir \u201cbonito\u201d (aunque a saber qu\u00e9 significa eso), sino de plasmar lo que se quiere decir de la manera que considere m\u00e1s eficaz, sin concesiones, desde la certidumbre de que siempre se puede expresar de otra y de que su manera no sintonizar\u00e1 con algunos lectores, si es que lo llegan a leer. Es en esa voluntad de estilo donde se cifra la cualidad moral de la escritura, que Mu\u00f1oz Molina, m\u00e1s all\u00e1 de que el contenido sobre lo que est\u00e9 escribiendo sea la denuncia de un exceso terrorista en Cisjordania o una fantas\u00eda humorista y borgiana sobre dos se\u00f1ores que se topan en la terminal de un aeropuerto, encarna hoy como muy pocos autores, en una obra forjada paso a paso, l\u00ednea a l\u00ednea, sin estridencias, casi en sordina, pero de una autoridad incontestable.<\/p>\n<p style=\"text-align: right;\">(<em>La sombra del cipr\u00e9s<\/em>, 21\/9\/2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No necesit\u00f3 el lector atento m\u00e1s que una novela \u2015Beatus ille, 1986\u2015 para darse cuenta de que se encontraba ante un autor que respiraba a su propio aire, con una propuesta narrativa que se separaba de las tendecias mayoritarias del momento \u2015garc\u00edamarquismo, minimalismo airado\u2015 con tanta discreci\u00f3n como voluntad. Aquella primera novela y la compilaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[314,407,600,608,679,789],"class_list":["post-767","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-cubos-con-hojas","tag-estilo","tag-hay-festival-segovia","tag-moral","tag-munoz-molina","tag-perfiles","tag-robinson"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=767"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/767\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}