{"id":785,"date":"2013-10-20T12:09:45","date_gmt":"2013-10-20T10:09:45","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=785"},"modified":"2013-10-20T12:09:45","modified_gmt":"2013-10-20T10:09:45","slug":"tres-en-uno","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/10\/20\/tres-en-uno\/","title":{"rendered":"Tres en uno"},"content":{"rendered":"<p>La Espiga de Honor de la presente SEMINCI ha reca\u00eddo en <a href=\"http:\/\/www.paulschrader.org\/\" target=\"_blank\" rel=\"external nofollow\"><strong>Paul Schrader,<\/strong><\/a> lo cual tiene pleno sentido en el marco de un festival de cine, que no es otra cosa que una reuni\u00f3n m\u00e1s o menos numerosa de cin\u00e9filos\/cin\u00e9fagos que ven y juzgan una serie de pel\u00edculas previamente elegidas. El hecho de juzgar es central en un festival \u2014sea del lado del p\u00fablico, sea del de los jurados oficiales\u2014, al punto absurdo de que en ocasiones se tiene la impresi\u00f3n de que el festival no es m\u00e1s que una excusa para el palmar\u00e9s. Premiar as\u00ed a uno de los \u00faltimos exponentes del dictum godardiano de que filmar pel\u00edculas no es otra cosa que hacer cr\u00edtica con una c\u00e1mara supone un acierto que desborda el marco estricto del m\u00e9rito f\u00edlmico de la obra de Schrader, con ser esta merecedora por s\u00ed misma del premio.<\/p>\n<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/10\/schrader-e1382263683154.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-786\" title=\"schrader\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/10\/schrader-e1382263683154.jpg\" alt=\"\" width=\"180\" height=\"116\" \/><\/a>Schrader pues ha seguido una carrera \u2014cr\u00edtico-guionista-director\u2014 tan l\u00f3gica como infrecuente. Lo m\u00e1s peculiar e interesante de esta elecci\u00f3n es que el cambiar de estadio no le ha hecho renunciar a los estadios anteriores. A\u00fan hoy sigue escribiendo guiones para otros y ejercitando la cr\u00edtica de texto. En el estadio inicial Schrader fogue\u00f3 la pluma bajo el amparo de la m\u00edtica <strong>Pauline Kael<\/strong>, a quien \u00e9l mismo califica de <<segunda madre>>. Como con su madre biol\u00f3gica la relaci\u00f3n no fue siempre f\u00e1cil \u2014sinteticemos diciendo que con Kael s\u00ed hubo reconciliaci\u00f3n premortem\u2014, pero no ha habido otra que haya determinado m\u00e1s medularmente la vida profesional de Schrader, incluidas la mantenida con <strong>Scorsese<\/strong> o su hermano <strong>Leonard<\/strong>.<\/p>\n<p>Los dos requisitos imprescindibles que ha de tener un cr\u00edtico son conocimiento de causa y honestidad; el uno sin el otro hace que la cr\u00edtica se caiga. Se detecta cuando un cr\u00edtico es bueno porque podemos discrepar de \u00e9l pero aun as\u00ed reconocemos la verdad de su postura, y en este sentido el rigor de los escritos de Schrader resulta impecable. En el que considero su \u00faltimo gran ensayo \u2014<em>Canon Fodder,<\/em> que podr\u00edamos traducir como \u2018<em>Canon morralla<\/em>\u2014, defiende la necesidad cinematogr\u00e1fica de un canon, esto es, de una jerarqu\u00eda del juicio. Lo cual hoy, en que el mantra de que toda opini\u00f3n vale lo mismo se ha extendido a velocidad de ADSL, es poco menos que una herej\u00eda.<\/p>\n<p>Schrader inaugur\u00f3 la segunda etapa con el guion de <em>Yakuza<\/em>, por el que recibe un past\u00f3n escandoloso y, m\u00e1s importante, le permite comenzar a trabajar con algunos de los directores j\u00f3venes m\u00e1s interesantes de los 70 hasta que topa con Scorsese, quien pone en escena el libreto de <em>Taxi driver<\/em> de una manera tan perfecta que hoy se hace inimaginable cualquier otra. Aparte de un idilio tormentoso con Scorsese, para quien escribir\u00eda otras dos joyitas y una cuchara de madera, <em>Taxi driver<\/em> permite a Schrader pasar a la tercera y \u00faltima etapa, detr\u00e1s de las c\u00e1maras, con el drama s\u00edndicocriminal <em>Blue collar<\/em>. Curiosamente en el guion de su debut como director se aparta Schrader un tanto de la concepci\u00f3n mametiana de contar la historia siguiendo a un personaje\/h\u00e9roe, que hab\u00eda mantenido hasta entonces y mantendr\u00eda luego casi siempre. <strong>Travis Bickle<\/strong>, <strong>Mishima<\/strong>, <strong>Jesucristo<\/strong>, <strong>Julian Kay<\/strong>\u2026 los personajes de Schrader est\u00e1n encerrados en sus propias contradicciones, en lucha con sus debilidades interiores, y a riesgo de resultar simplista creo que esta es la raz\u00f3n fundamental, m\u00e1s que la <<oscuridad>> de las historias que cuenta, que le ha hecho caer en semidesgracia, porque nadie en Hollywood parece hoy dispuesto a promover complejidades, porque los personajes han de ser cuanto m\u00e1s recortaditos y blanquinegros, mejor, y porque para dilemas morales el p\u00fablico ya tiene bastante con elegir entre la fila ocho o la nueve. El otrora ni\u00f1o de oro de la industria ha tenido que recurrir a la financiaci\u00f3n on-line para sacar adelante <em>The canyons<\/em>, su \u00faltimo empe\u00f1o tras el visor. Por suerte para nosotros SEMINCI no opina como Hollywood.<\/p>\n<p style=\"text-align: right;\">(<em>La sombra del cipr\u00e9s<\/em>, 19\/10\/2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Espiga de Honor de la presente SEMINCI ha reca\u00eddo en Paul Schrader, lo cual tiene pleno sentido en el marco de un festival de cine, que no es otra cosa que una reuni\u00f3n m\u00e1s o menos numerosa de cin\u00e9filos\/cin\u00e9fagos que ven y juzgan una serie de pel\u00edculas previamente elegidas. El hecho de juzgar es [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,10],"tags":[176,310,666,825,907],"class_list":["post-785","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-desde-la-pantalla","tag-cine","tag-espiga-de-honor","tag-paul-schrader","tag-seminci-2013","tag-trayectoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=785"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/785\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}