{"id":815,"date":"2013-12-09T21:15:30","date_gmt":"2013-12-09T20:15:30","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=815"},"modified":"2013-12-09T21:15:30","modified_gmt":"2013-12-09T20:15:30","slug":"letras-como-punos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2013\/12\/09\/letras-como-punos\/","title":{"rendered":"Letras como pu\u00f1os"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/12\/el-combate-e1386619980971.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-816\" title=\"el combate\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/12\/el-combate-e1386619980971.jpg\" alt=\"\" width=\"180\" height=\"273\" \/><\/a><a title=\"foreman-al\u00ed, zaire 1974\" href=\"http:\/\/www.youtube.com\/watch?v=55AasOJZzDE\" target=\"_blank\" rel=\"external nofollow\">El combate entre <strong>Al\u00ed<\/strong> y <strong>Foreman<\/strong> en Kinshasa<\/a> parec\u00eda dise\u00f1ado para la pluma de <strong>Mailer<\/strong>, cuyas pasiones \u00e9pica y pol\u00edtica encontraban respectivamente en el boxeo y en el problema del negro los puntos de partida ideales para liberarse. En este sentido, el reci\u00e9n nacido Zaire del dictador <strong>Mobutu<\/strong>, en pleno coraz\u00f3n del \u00c1frica Negra, si no el entorno m\u00e1s propicio para la pr\u00e1ctica del deporte ni para la cobertura informativa, resultaba la s\u00edntesis perfecta de ambas pasiones, el escenario que cualquier reportero hubiera elegido por sus resonancias dram\u00e1ticas. El combate as\u00ed, siendo el centro del encargo, es mucho m\u00e1s que un combate, es por un lado casi una excusa para tratar esas otras pasiones\/obsesiones y por otro el Norte que no se puede perder nunca de vista y hacia el que Mailer, utilizando todos los recursos de su muy surtido saco de novelista, va construyendo una tensi\u00f3n que estalla en el cl\u00edmax de los cap\u00edtulos 12 a 15 con el relato del intercambio de pu\u00f1os.<\/p>\n<p>Alguien dijo que solo un genio puede descubrir a otro genio. Y Mailer nos muestra al genio de Al\u00ed en toda su parcial y trunca grandeza: un retrato afectuoso sin dejar de ser cr\u00edtico. El juego de pies incomparable y la fanfarroner\u00eda grosera, la lectura psicol\u00f3gica del adversario y la ch\u00e1chara escasamente deportiva, la bondad infantil y el egotismo delirante. Y con el ego hemos llegado al n\u00facleo y motor del relato. Aparte de una cr\u00f3nica subjetiva,<em> El combate<\/em> es un estudio sobre el ego. Al retratar a Al\u00ed, Mailer se est\u00e1 retratando a s\u00ed mismo \u2014<<el campe\u00f3n de los escritores>>\u2014, y a s\u00ed mismo se aplica el mismo tratamiento bifocal: no oculta que puede resultar rid\u00edculo, excesivo, injustamente visceral; tampoco que la riqueza de su prosa y estilo inimitables ser\u00e1n considerados un referente obligado en las letras americanas. Pero ni Al\u00ed ni Mailer ten\u00edan problema alguno con sus respectivos egos. Quienes lo ten\u00edan eran los otros boxeadores y miembros de la crema literariocultural americana. El Nuevo Periodismo hizo del ego del autor el filtro de la narraci\u00f3n. Pero si una <a title=\"reflejos de joan didion\" href=\"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/2012\/12\/04\/reflejos-de-joan-didion\/\" target=\"_blank\"><strong>Joan Didion<\/strong><\/a> o un <strong>Gay Talese<\/strong> prefieren, aun siendo parte de lo narrado, diluir sus personas en la narraci\u00f3n \u2014sin sacrificar por ello un \u00e1pice de la singularidad de su estilo\u2014, Mailer se sit\u00faa en primer plano, personaje activo que con sus acciones determina en parte el curso de los acontecimientos.<\/p>\n<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/12\/mailer-ali-e1386620050865.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-817\" title=\"mailer-ali\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2013\/12\/mailer-ali-e1386620050865.jpg\" alt=\"\" width=\"180\" height=\"129\" \/><\/a>No siempre en <em>El combate<\/em> el estilo de Mailer es tan fluido de seguir como ser\u00eda deseable, sobre todo en las reflexiones y soliloquios; espesura que es en parte reflejo de las interrupciones, rectificaciones, exploraciones de su propio pensamiento \u2014verbigracia, cuando intenta explicar la diferencia entre <<fuerzas>> y <<seres>> de la filosof\u00eda bant\u00fa\u2014 y en parte de la descomunal capacidad receptiva que posee, que el escalpelo del estilo a veces no logra domesticar. El ejemplo m\u00e1s notorio del torrente maileriano se halla en la inagotable capacidad comparativa de que hace gala. El s\u00edmil es el otro gran protagonista de <em>El combate<\/em>. Entre s\u00edmil y s\u00edmil, \u00bfqu\u00e9 mete Mailer? Otro s\u00edmil. Sensuales, ir\u00f3nicos, de referencias animales\u2026 Son muchos pero rara vez gratuitos, con no poca frecuencia deslumbrantes y m\u00e1s reveladores que una descripci\u00f3n de diez l\u00edneas: <<[Al\u00ed] Parec\u00eda aburrido. Pon\u00eda de manifiesto, al trabajar, todo el sombr\u00edo entusiasmo del marido que se obliga a s\u00ed mismo a hacerle el amor a su mujer en medio de la m\u00e1s densa indiferencia carnal.>>; <<Al\u00ed procedi\u00f3 a golpear a Foreman con una combinaci\u00f3n tan poco frecuente como el plutonio.>><\/p>\n<p><em>El combate<\/em> es pues un reportaje inexcusable para todo aquel aficionado al boxeo, pero sobre todo inexcusable para todo amante del periodismo literario. Es una l\u00e1stima que esta nueva y necesaria edici\u00f3n no haga justicia al material que ofrece. Aparte de la habitual, epid\u00e9mica tendencia entre los traductores de hacer del espa\u00f1ol un idioma tan posesivo como el ingl\u00e9s \u2014<<\u2026 no hab\u00eda vuelto a ver a Foreman hasta \u2018su\u2019 segundo asalto contra <strong>Norton<\/strong>>> en vez de <<el>>: el asalto no es de Foreman, si acaso de Foreman y Norton\u2014, podemos encontrarnos con desatinos como <<mal educado>> por <<maleducado>>, <<anom\u00eda>> por <<anomia>>, <<whiski>> por <<whisky o g\u00fcisqui>>, o <<contraceptivos>> por <<anticonceptivos>>; o como omitir incontables veces la preposici\u00f3n <<de>> tras el verbo <<deber>> cuando la frase tiene un sentido de probabilidad y no de obligaci\u00f3n; o con el capricho de verter el hist\u00f3rico grito de guerra de Al\u00ed como <<aguijonea como una abeja>> en lugar del m\u00e1s sencillo y conocido <<pica>>. Y todo ello sin contar con una pl\u00e9tora de erratas entre las que destaca con brillo propio el cambio que se hace del nombre del mimo <strong>Marcel Marceu<\/strong>, al que se le suprime la ele. Faltas todas que esperemos se subsanen en pr\u00f3ximas ediciones de un volumen que, por relevancia hist\u00f3rica y altura period\u00edstica, sin duda merece alcanzar.<\/p>\n<p style=\"text-align: right;\">(<em>La sombra del cipr\u00e9s<\/em>, 7\/12\/2013)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El combate entre Al\u00ed y Foreman en Kinshasa parec\u00eda dise\u00f1ado para la pluma de Mailer, cuyas pasiones \u00e9pica y pol\u00edtica encontraban respectivamente en el boxeo y en el problema del negro los puntos de partida ideales para liberarse. En este sentido, el reci\u00e9n nacido Zaire del dictador Mobutu, en pleno coraz\u00f3n del \u00c1frica Negra, si [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[124,279,377,534,605,629,632,773,956],"class_list":["post-815","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-cubos-con-hojas","tag-boxeo","tag-el-combate","tag-george-foreman","tag-libros","tag-muhammad-ali","tag-norman-mailer","tag-nuevo-periodismo","tag-resenas","tag-zaire"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=815"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/815\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}