{"id":82,"date":"2011-09-30T20:31:07","date_gmt":"2011-09-30T18:31:07","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=82"},"modified":"2011-09-30T20:31:07","modified_gmt":"2011-09-30T18:31:07","slug":"platform","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2011\/09\/30\/platform\/","title":{"rendered":"Platform"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"\/\/i-7.vcimg.com\/c4e3d8b83f2029a91711aaca42bae8b7214614%28120x170%29\/thumb.jpg\" alt=\"\" width=\"120\" height=\"170\" \/>Los planos frontales, est\u00e1ticos, adoptan la mirada del espectador teatral; se dan sobre todo al principio, cuando la compa\u00f1\u00eda est\u00e1 unida; seg\u00fan esta se desintegra se comienzan a incorporar, siempre de manera sutil\u00edsima, a la paleta de los planos, por as\u00ed llamarla, y creo no es err\u00f3neo llamarla as\u00ed, movimientos de c\u00e1mara, lentos desplazamientos, oblicuidades. Un gusto en la realizaci\u00f3n, en definitiva, delicad\u00edsimo. El film procede por s\u00edntesis, un poco a la manera de <strong>Eisenstein<\/strong> pasado por <strong>Ozu<\/strong>, sin ning\u00fan \u00e9nfasis gratuito; el film gusta de mostrar no solo el durante sino tambi\u00e9n el antes y el despu\u00e9s, y en esto se separa del ruso, de los principios de la dramaturgia occidental cl\u00e1sica. El uso del color es asimismo magistral: modestamente preciso. Punto y aparte merece la carga sem\u00e1ntica con que se dota al tabaco; el cigarrillo en este caso no es mero, como suele, elemento de <em>atrezzo<\/em> en el que el actor refugia sus inseguridades, el cigarrillo representa al mismo tiempo un reducto de libertad en el que creen los personajes y una concesi\u00f3n que el Estado les proporciona para mantenerlos anestesiados, una concesi\u00f3n menor que los inhiba de aspirar a otras m\u00e1s sustanciales (esto es lo que lat\u00eda, estoy seguro, tras la promoci\u00f3n de <strong>Mao<\/strong> del tabaco, cuyo fin el film refleja). No recuerdo un actor que fume mejor &#8211; con mayor naturalidad, con m\u00e1s justo <em>timing<\/em> de la calada &#8211; que <strong>Hong Wei Wang<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los planos frontales, est\u00e1ticos, adoptan la mirada del espectador teatral; se dan sobre todo al principio, cuando la compa\u00f1\u00eda est\u00e1 unida; seg\u00fan esta se desintegra se comienzan a incorporar, siempre de manera sutil\u00edsima, a la paleta de los planos, por as\u00ed llamarla, y creo no es err\u00f3neo llamarla as\u00ed, movimientos de c\u00e1mara, lentos desplazamientos, oblicuidades. [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[176,773],"class_list":["post-82","post","type-post","status-publish","format-standard","hentry","category-apuntes","category-desde-la-pantalla","tag-cine","tag-resenas"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}