{"id":847,"date":"2014-02-08T11:54:33","date_gmt":"2014-02-08T10:54:33","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=847"},"modified":"2014-02-08T11:54:33","modified_gmt":"2014-02-08T10:54:33","slug":"mortal-conformismo","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2014\/02\/08\/mortal-conformismo\/","title":{"rendered":"Mortal conformismo"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2014\/02\/psh-e1391856652709.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-848\" title=\"psh\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2014\/02\/psh-e1391856652709.jpeg\" alt=\"\" width=\"180\" height=\"168\" \/><\/a>M\u00e1s peligrosa que la cruzada voceona de los autodesignados guardianes de la moral \u2014\u00a1Esto es lo que pasa! \u00a1Esto!\u2014 es la extendida y bienintencionada incomprensi\u00f3n ante un hecho que, en definitiva, no es sino el precipitado fatal de una situaci\u00f3n que escapa al control de la v\u00edctima. Tres hijos, un Oscar, talento excepcional y la oportunidad de explorarlo y expresarlo\u2026 <<Si lo ten\u00eda todo>>, ha sido el comentario un\u00e1nime tras conocerse la noticia. Bien, resulta evidente que <<todo>> no lo ten\u00eda, que le faltaba aquello que \u00e9l consideraba m\u00e1s esencial y que esa falta lo llev\u00f3 adonde lo llev\u00f3. Y adonde lo llev\u00f3 es un territorio en el que el hecho irreversible de la muerte es un habitante con el que uno se puede topar con mayor probabilidad. La cuesti\u00f3n no es si la muerte del actor fue o no voluntaria, sino por qu\u00e9 la muerte parece bastarnos como explicaci\u00f3n final cuando en realidad deber\u00eda ser el desencadenante de la b\u00fasqueda. De los muchos art\u00edculos que he le\u00eddo no he encontrado ninguno que siquiera estableciera un marco general, una hip\u00f3tesis basada en hechos sobre los motivos de la depresi\u00f3n, o de la personalidad adictiva, motivos ex\u00f3genos o end\u00f3genos, que padec\u00eda o ten\u00eda el actor. Lo m\u00e1s que se ha llegado a decir es que hab\u00eda entrado y salido de una cl\u00ednica de rehabilitaci\u00f3n, que de joven se met\u00eda cuanto se le pon\u00eda a mano \u2014y esto porque lo dijo \u00e9l\u2014. Pero nada del por qu\u00e9, ninguna causa posible. <<Si lo ten\u00eda todo>>. Con este conformismo al final se les est\u00e1 haciendo el juego a los guardianes de la moral (moralina), pues se termina uno resignando al detonante inmediato, que es la droga, y concluyendo que suprimida la droga, suprimido el problema. Pero \u00bfqu\u00e9 es eso que no ten\u00eda y lo llev\u00f3 a la evasi\u00f3n sistem\u00e1tica del alcohol y la hero\u00edna \u2014y conyunturalmente a la muerte? Eso, y no si ten\u00eda 50 o 70 papelinas en su apartamento, es lo que deber\u00eda investigarse. Las papelinas por s\u00ed solas no son m\u00e1s que amarillismo tranquilizador.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 6\/2\/2014)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s peligrosa que la cruzada voceona de los autodesignados guardianes de la moral \u2014\u00a1Esto es lo que pasa! \u00a1Esto!\u2014 es la extendida y bienintencionada incomprensi\u00f3n ante un hecho que, en definitiva, no es sino el precipitado fatal de una situaci\u00f3n que escapa al control de la v\u00edctima. Tres hijos, un Oscar, talento excepcional y la [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[66,153,236,332,529,604,691,839],"class_list":["post-847","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","tag-apariencia","tag-causas","tag-depresion","tag-felicidad","tag-libertad","tag-muerte","tag-philip-seymour-hoffman","tag-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=847"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/847\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}