{"id":996,"date":"2015-03-12T15:56:12","date_gmt":"2015-03-12T14:56:12","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=996"},"modified":"2015-03-12T15:56:12","modified_gmt":"2015-03-12T14:56:12","slug":"ana-frank","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2015\/03\/12\/ana-frank\/","title":{"rendered":"ana frank"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/03\/ana-frank-blog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-997\" title=\"ana frank blog\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/03\/ana-frank-blog.jpg\" alt=\"\" width=\"220\" height=\"293\" \/><\/a>Se cumplen 70 a\u00f1os de la muerte de <strong>Ana Frank <\/strong>y la efem\u00e9ride se ha aprovechado \u2014sin hacer referencia expresa a ella\u2014 para anunciar que por primera vez una productora alemana ha sido autorizada a rodar la biograf\u00eda de la ni\u00f1a. Es el \u00faltimo, pero con seguridad por breve tiempo, producto de una industria que utiliza el Holocausto como despensa inagotable de la que nutrirse. Auschwitz se ha convertido en un g\u00e9nero literario. Pel\u00edculas, novelas, obras de teatro\u2026 hemos llegado a un nivel de saturaci\u00f3n que sin embargo seguimos tragando encantados. Como si de un aval indudable se tratase, si un producto cultural lleva adosado alg\u00fan evento que lo relacione, siquiera oblicuamente, con el genocidio jud\u00edo, le otorgamos de entrada un plus de calidad, cuando la experiencia nos indica deber\u00eda ser al contrario. Toda esta industria no trata de comprender lo incomprensible, sino que se queda en un pintorequismo \u2014m\u00e1s o menos elaborado\u2014 que casi indefectiblemente ofrece la m\u00e1s barata \u2014pero lucrativa\u2014 pornograf\u00eda emocional. Por cada <strong>William Styron <\/strong>obtenemos mil <strong>Spielbergs<\/strong>, y encima sin el dominio t\u00e9cnico de Spielberg, y as\u00ed hemos pasado de la banalidad del mal de <strong>Hannah Arendt <\/strong>a la banalizaci\u00f3n del sufrimiento. El gancho comercial consiste en acentuar los aspectos m\u00e1s truculentos de la peripecia que se narre, y a esperar a hacer caja, a sabiendas de que el Holocausto posee una suerte de bula cr\u00edtica que hace que nadie se atreva a denunciar el producto por muy anodino o descarado que este sea. Hay m\u00e1s integridad art\u00edstica en diez minutos al azar de \u2018Malditos bastardos\u2019 o en el chiste de <strong>Woody Allen<\/strong> \u2014<<Cuando escucho a <strong>Wagner<\/strong> me entran ganas de invadir Polonia>>\u2014 que en las mil y pico p\u00e1ginas del novel\u00f3n de turno que promociona <strong>Oprah Winfrey<\/strong>. Tambi\u00e9n la hay en la mirada limpia que Ana Frank dej\u00f3 para siempre en su cr\u00f3nica de la casa de atr\u00e1s, cuyas p\u00e1ginas dejan entrever que quiz\u00e1 no estar\u00eda del todo satisfecha con el papel de m\u00e1rtir que le ha sido asignado.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 12\/3\/2015)<\/p>\n<p style=\"text-align: left;\"><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se cumplen 70 a\u00f1os de la muerte de Ana Frank y la efem\u00e9ride se ha aprovechado \u2014sin hacer referencia expresa a ella\u2014 para anunciar que por primera vez una productora alemana ha sido autorizada a rodar la biograf\u00eda de la ni\u00f1a. Es el \u00faltimo, pero con seguridad por breve tiempo, producto de una industria que [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7,8,10],"tags":[57,61,221,422,839],"class_list":["post-996","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-columnas","category-cubos-con-hojas","category-desde-la-pantalla","tag-ana-frank","tag-aniversario","tag-cultura","tag-holocausto","tag-sociedad"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/996\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}