{"id":998,"date":"2015-03-19T15:56:47","date_gmt":"2015-03-19T14:56:47","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/enfaserem\/?p=998"},"modified":"2015-03-19T15:56:47","modified_gmt":"2015-03-19T14:56:47","slug":"cifu","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/2015\/03\/19\/cifu\/","title":{"rendered":"Cifu"},"content":{"rendered":"<p><a href=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/03\/juan-claudio-cifuentes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-999\" title=\"juan claudio cifuentes\" src=\"\/enfaserem\/wp-content\/uploads\/sites\/14\/2015\/03\/juan-claudio-cifuentes.jpg\" alt=\"\" width=\"220\" height=\"164\" \/><\/a>La \u00fanica vez que habl\u00e9 con <strong>Juan Claudio Cifuentes <\/strong>fue por tel\u00e9fono. Lo llam\u00e9 a su emisora con la misma esperanza de encontrarlo que la de quien se ve por compromiso obligado a jugar un d\u00e9cimo de loter\u00eda de que le toque. Pero se puso, y aunque el contacto, para ayudar a la UVa a difundir el Universijazz, no pudo materializarse \u2014ya ten\u00eda los programas del verano <<en el disco duro>>\u2014, Cifu me acribill\u00f3 a preguntas sobre los participantes y las fechas y la longevidad del festival y\u2026 Antes lo hab\u00eda visto dos veces, lejano en un concierto y a pocos metros en una de las jam sessions de Canciller Ayala, en Vitoria; aqu\u00ed, tras la pausa del tr\u00edo contratado alguien pidi\u00f3 que el legendario <strong>Jimmy Cobb<\/strong>, que deb\u00eda de andar perdido en alg\u00fan rinc\u00f3n, se subiera a la tarima y agarrase los palos. Cifu, al o\u00edr la petici\u00f3n, se volvi\u00f3 desde la barra y comenz\u00f3 a gritar el nombre del baterista con gestos de controlador a\u00e9reo en la cubierta de un transatl\u00e1ntico militar. Y es que fue gracias a una pasi\u00f3n solo comparable a su generosidad que Cifu se mantuvo durante m\u00e1s de cuarenta a\u00f1os difundiendo en Espa\u00f1a un virus, el jazz, contra el que una vez inoculado no hay antibi\u00f3tico posible. Tuvo que vencer no pocas vacunas tenaces \u2014horarios insomnes, cambios o cancelaciones en la cadena de turno, indiferencia institucional\u2014, y la batalla contin\u00faa, pero los no pocos infectados le estaremos por siempre agradecidos. La otra gran virtud comunicadora de Cifu fue la cercan\u00eda. Sab\u00eda de jazz m\u00e1s que nadie, y sin embargo no denotaba nunca superioridad alguna: lleg\u00f3 a hacer de la carraspera algo entra\u00f1able. Y s\u00ed, pod\u00eda ser tan cr\u00edtico como el que m\u00e1s, pero nunca a costa de sacrificar la honestidad, su independencia.<\/p>\n<p>En los programas de homenaje por el aniversario del fallecimiento de un m\u00fasico, sol\u00eda referir que el homenajeado estar\u00eda tocando en la <<big band de all\u00e1 arriba>>. De ser as\u00ed, no cabe duda de que Cifu estar\u00e1 en primera fila sin dejar de seguir el ritmo con el pie.<\/p>\n<p style=\"text-align: right;\">(<em>El Norte de Castilla<\/em>, 19\/3\/2015)<\/p>\n<p style=\"text-align: left;\"><a title=\"@enfaserem\" href=\"https:\/\/twitter.com\/enfaserem\" target=\"_blank\" rel=\"external nofollow\">@enfaserem<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00fanica vez que habl\u00e9 con Juan Claudio Cifuentes fue por tel\u00e9fono. Lo llam\u00e9 a su emisora con la misma esperanza de encontrarlo que la de quien se ve por compromiso obligado a jugar un d\u00e9cimo de loter\u00eda de que le toque. Pero se puso, y aunque el contacto, para ayudar a la UVa a [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6,7],"tags":[192,465,490,745,759],"class_list":["post-998","post","type-post","status-publish","format-standard","hentry","category-ha-ocurrido-esta-ocurriendo-ocurrira","category-claves-sonoras","category-columnas","tag-comunicacion","tag-jazz","tag-juan-claudio-cifuentes","tag-radio","tag-recuerdo"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/comments?post=998"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/posts\/998\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/media?parent=998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/categories?post=998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/enfaserem\/wp-json\/wp\/v2\/tags?post=998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}