{"id":14,"date":"2009-10-25T07:49:00","date_gmt":"2009-10-25T07:49:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/jorge-praga\/?p=14"},"modified":"2009-10-25T07:49:00","modified_gmt":"2009-10-25T07:49:00","slug":"septiembre-del-75-octubre-2009","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/2009\/10\/25\/septiembre-del-75-octubre-2009\/","title":{"rendered":"Septiembre del 75, Octubre de 2009"},"content":{"rendered":"<p>Eran otros tiempos en este pa\u00eds. Los trae Adolfo Dufour en su documental &#8216;Septiembre del 75&#8217;, enhebrado sobre uno de los cinco fusilados en esa fecha, los \u00faltimos fusilados de franquismo. Xos\u00e9 Humberto Baena ten\u00eda entonces mi edad, y ahora tambi\u00e9n compartir\u00edamos a\u00f1os de no haberse cruzado en su camino la sangrienta represi\u00f3n con que se despidi\u00f3 la dictadura. El documental me pertenece, respiro por sus im\u00e1genes, veo de nuevo a los represores y a sus c\u00f3mplices, vuelvo a pensar en esa palada de arena sobre el pasado que fue la Transici\u00f3n, y que ha tapado durante 34 a\u00f1os historias como \u00e9sta, la de la vida truncada de Xos\u00e9 Humberto Baena.<br \/>\nMe pregunto si las nuevas generaciones reconocer\u00e1n a esas gentes y a esas calles como las mismas que siguen albergando sus vidas. No tanto si conocen los hechos del final del franquismo y el arranque de la transici\u00f3n; no, la cuesti\u00f3n es si los perciben como propios, todav\u00eda latentes, decisorios de la vida de sus padres y de tantas otras personas cercanas. Y tambi\u00e9n presentes en la actualidad, en los miedos, en las vejaciones sin mitigar, en la obediencia al dictado de que es mejor no revolver los hechos, no revolver nada.<br \/>\nEl borrado ha sido eficaz, supongo. Las palabras esconden sus significados de anta\u00f1o: militancia pol\u00edtica, lucha armada, manifestaciones, saltos, libertad, obreros, justicia. Otras terribles han desaparecido del todo, sin que nadie haya cargado con su suciedad: picana, s\u00f3tanos de la DGS, Billy el Ni\u00f1o, Conesa, disparos al aire que matan. Y todas envueltas en violencia, en la violencia que engendra violencia, seg\u00fan la cita de Esquilo con que se abre la pel\u00edcula. Una violencia que ejerc\u00eda implacablemente el estado franquista y que ten\u00eda respuesta en grupos organizados y clandestinos.<IMG src=\"\/jorge-praga\/wp-content\/uploads\/sites\/8\" id=\"img_0\" class=\"imgizqda\"><br \/>\nXos\u00e9 Humberto Baena tambi\u00e9n ha sido borrado. Nadie responde a las preguntas sobre la farsa legal que le conden\u00f3 y fusil\u00f3. Los tribunales devuelven las peticiones sobre la revisi\u00f3n de su caso; tampoco las lejanas instancias internacionales se sienten implicadas o concernidas. Su nombre llega hasta estas l\u00edneas por el empe\u00f1o de su familia: su padre dej\u00f3 una emotiva carta a los nietos relatando los hechos, y su hermana no ha dejado de remover y preguntar. No pide nada, s\u00f3lo la reparaci\u00f3n moral y jur\u00eddica de la memoria de Xos\u00e9 Humberto. Y en esa estela se construye el documental de Adolfo Dufour, austero y estricto en su planteamiento de dejar hablar a los protagonistas sobre una delgada y l\u00edrica voz del narrador.<br \/>\nXos\u00e9 Humberto en los d\u00edas previos a su fusilamiento dio cuenta en las cartas a sus padres de las lecturas que hac\u00eda en la c\u00e1rcel. Un chaval templado, que pod\u00eda leer a Blas de Otero cuando sab\u00eda que su vida se acababa. Y anota la impresi\u00f3n que le causaron unos versos del poeta, que ahora se ajustan perfectamente al empuje que le da esta obra: &#8220;Si he perdido la vida (&#8230;) me queda la palabra&#8221;. Su palabra, enhebrada en im\u00e1genes y testimonios, le devuelve, nos devuelve, lo que se quiso y se quiere borrar. Tachar, m\u00e1s que olvidar.<br \/>\nLarga, larga ovaci\u00f3n del p\u00fablico. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eran otros tiempos en este pa\u00eds. Los trae Adolfo Dufour en su documental &#8216;Septiembre del 75&#8217;, enhebrado sobre uno de los cinco fusilados en esa fecha, los \u00faltimos fusilados de franquismo. Xos\u00e9 Humberto Baena ten\u00eda entonces mi edad, y ahora tambi\u00e9n compartir\u00edamos a\u00f1os de no haberse cruzado en su camino la sangrienta represi\u00f3n con que [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-14","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/posts\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/posts\/14\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/media?parent=14"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/categories?post=14"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/tags?post=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}