{"id":20,"date":"2009-10-30T08:43:00","date_gmt":"2009-10-30T08:43:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/jorge-praga\/?p=20"},"modified":"2009-10-30T08:43:00","modified_gmt":"2009-10-30T08:43:00","slug":"cine-orquestado","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/2009\/10\/30\/cine-orquestado\/","title":{"rendered":"Cine orquestado"},"content":{"rendered":"<p><IMG src=\"\/jorge-praga\/wp-content\/uploads\/sites\/8\" id=\"img_0\" class=\"imgdcha\">Nuevamente llega a la Seminci un experimento de acompa\u00f1amiento musical en directo.En los \u00faltimos a\u00f1os ha sido bastante frecuente. Ahora se ha aprovechado la partitura que expresamente compuso Camille Saint-Sa\u00ebns para &#8220;El asesinato del duque de Guisa&#8221;, obra de 1908, que aparece por las historias del cine como un intento de sacar al nuevo arte de las barracas populares. Detr\u00e1s estaba un grupo de nombre pomposo, Soci\u00e9t\u00e9 Cin\u00e9matographique des Auteurs et Gens de Lettres, que se procur\u00f3 guionistas, directores, actores teatrales conocidos, y tambi\u00e9n al m\u00fasico m\u00e1s prestigioso del momento. Film d&#8217;Art se denomin\u00f3 el movimiento, que dur\u00f3 poco. A juzgar por lo visto ayer, hubo justicia.<br \/>\nLa pel\u00edcula es arqueolog\u00eda aburrida, lo que no es ninguna redundacia. Otras arqueolog\u00edas de esa \u00e9poca, incluso diez a\u00f1os atr\u00e1s, traen obras que siguen conservando el magnetismo de los primeros tiempos, esa virginidad de las miradas que est\u00e1 en el p\u00e1lpito de lo real de tantos Lumi\u00e8re o en la gracia on\u00edrica de M\u00e9li\u00e8s. No hace falta ning\u00fan plus de historiador para emocionarse con ellas. Pero este asesinato del duque es puro teatro filmado sin ninguna de las ventajas del teatro. Actores frontales a la c\u00e1mara, reducci\u00f3n del espacio al escenario, ausencia total de montaje salvo en un par de cambios de habitaci\u00f3n que exigieron un esfuerzo de raccord. Y hacia el final se echa mano del truco de la parada de c\u00e1mara, puesto en marcha por M\u00e9li\u00e8s doce a\u00f1os antes. El animoso presentador (con \u00e9l la sesi\u00f3n lleg\u00f3 casi a la hora, cuando la pel\u00edcula s\u00f3lo tiene 17 minutos) insisti\u00f3 en que luego los americanos copiaron la idea, y la explotaron comercialmente. No estoy nada de acuerdo. Edwin S. Porter ya hab\u00eda desarrollado esfuerzos de montaje unos a\u00f1os antes, David Wark Griffith comenzaba su carrera en esa misma estela de crear un tiempo y espacio propios para la pantalla, esfuerzo que ni se huele en este mamotreto de Film d&#8217;Art.<br \/>\n\u00bfY la m\u00fasica? Porque \u00e9sa era la gracia de la sesi\u00f3n, y yo me he ido hacia el excursus hist\u00f3rico de l\u00edneas atr\u00e1s. La m\u00fasica delante de la pantalla, y no s\u00f3lo por la distribuci\u00f3n f\u00edsica que tuvimos en la sala, es una inversi\u00f3n de los elementos. Cuando he asistido a sesiones con int\u00e9rpretes en directo el saldo suele ser el mismo: a los dos o tres minutos de iniciada la proyecci\u00f3n, si todo va bien, te olvidas del pianista, aunque te moleste su flexo encendido encima del piano. La m\u00fasica se disuelve en la imagen, y es dif\u00edcil, incluso contraproducente, dedicarle atenci\u00f3n expl\u00edcita. Ayer ten\u00edamos la ventaja de que la pantalla era prescindible, as\u00ed que hubo margen para fijarse en la buena partitura y la cuidada interpretaci\u00f3n de la orquesta, en el funcionamiento de esas convenciones misteriosas que exigen un tipo de ritmo e instrumentaci\u00f3n para cada atm\u00f3sfera narrativa. \u00bfEs una convenci\u00f3n acumulada a lo largo de los a\u00f1os, o bien hay sonidos que objetivamente arrastran tensi\u00f3n, o persecuciones, o amor? Saint-Sa\u00ebns compuso la partitura cuando apenas si hab\u00eda tradici\u00f3n cinematogr\u00e1fica, y sus sonidos son perfectamente equiparables a los que hoy se har\u00edan. El cine arrancaba entonces, pero la m\u00fasica llevaba siglos en el escenario detr\u00e1s de los sentimientos y movimientos humanos.<br \/>\nQu\u00e9 bonito hubiera sido ver, y sobre todo o\u00edr, una segunda vez la proyecci\u00f3n. Supo a poco. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevamente llega a la Seminci un experimento de acompa\u00f1amiento musical en directo.En los \u00faltimos a\u00f1os ha sido bastante frecuente. Ahora se ha aprovechado la partitura que expresamente compuso Camille Saint-Sa\u00ebns para &#8220;El asesinato del duque de Guisa&#8221;, obra de 1908, que aparece por las historias del cine como un intento de sacar al nuevo arte [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-20","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/posts\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/posts\/20\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/media?parent=20"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/categories?post=20"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/jorge-praga\/wp-json\/wp\/v2\/tags?post=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}