{"id":157,"date":"2013-09-09T17:14:24","date_gmt":"2013-09-09T16:14:24","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/lacanaleja\/?p=157"},"modified":"2013-09-09T17:14:24","modified_gmt":"2013-09-09T16:14:24","slug":"lo-que-realmente-importa","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/2013\/09\/09\/lo-que-realmente-importa\/","title":{"rendered":"Lo que realmente importa"},"content":{"rendered":"<p>La vuelta al cole municipal no ha podido ser m\u00e1s abrupta. Como escolares que regresan de mal humor a las aulas despu\u00e9s de un verano de sol, piscina, pueblo, playa o donde narices haya estado cada uno, la han montado. Cruce de palabras y plante en el pleno y r\u00e9plica y contrarr\u00e9plica en los d\u00edas posteriores. Todo un ejercicio ejemplar de c\u00f3mo ha de hacerse pol\u00edtica para y por los ciudadanos. Un modelo de conducta que dista y mucho de lo que se espera de quienes en otras ocasiones se les llena la boca con uno de los \u00faltimos topicazos de la cosa p\u00fablica: vamos a hablar de lo que importa.<br \/>\nS\u00ed, de lo que importa al personal; de lo que nos importa a usted y a m\u00ed, de lo que importa a quienes de una forma disciplinada y, a veces, adocenada, nos rascamos el bolsillo para mantener este tinglado de administraciones y administracioncillas. Casi medio mill\u00f3n de tipos y tipas que nos alegran la vida con sus deciones, tres veces m\u00e1s que m\u00e9dicos o polic\u00edas, con unos costes salariales disparados hasta el infinito. Una ganga de pa\u00eds. Desde diputados y senadores hasta responsables de cabildos, diputaciones o mancomunidades; desde cargos de confianza hasta representantes en toda suerte de entidades p\u00fablicas, algunas de muy dudosa utilidad. Todo para superar en esta loca carrera a pa\u00edses que tienen el doble de poblaci\u00f3n que nosotros y la mitad de pol\u00edticos, naciones por otra parte nada sospechosas de gestionar mal sus econom\u00edas, como Alemania.<br \/>\nY lo que verdaderamente importa al ciudadano es eso, que nos gestionen bien nuestros cuatro duros o lo que quedan de ellos, que ya que lo tenemos que pagar y no de forma voluntaria, al menos que lo gasten con cabeza y, por supuesto, con honradez. Y en esto \u00faltimo est\u00e1 incluido no solo no meter la mano en el caj\u00f3n, sino tambi\u00e9n trabajar, esforzarse e irse a casa a dormir con la conciencia tranquila. Porque tan indigno es quien roba como quien no se hace digno del esfuerzo de todos sus compatriotas para mantener su sueldo. A esto se a\u00f1aden quienes ocupan puestos \u2013que me temo que son bastantes m\u00e1s de los que creemos\u2013 absolutamente in\u00fatiles, sin contenido, sin ocupaci\u00f3n efectiva, que les recuerdo es un derecho del trabajador.<br \/>\nDir\u00e1n que tambi\u00e9n he vuelto de vacaciones con ganas de montarla, como nuestros amigos del ayuntamiento segoviano. Pues, miren que no, que nada m\u00e1s lejos de mi intenci\u00f3n y que, adem\u00e1s eso no es lo que realmente importa. Y si me apuran ustedes, dir\u00e1n que esto del n\u00famero de pol\u00edticos es asunto manido y con muchas posibilidades de acariciar la demagogia. Pues, quiz\u00e1, pero no me digan que no les pide el cuerpo el universal y socorrido derecho al pataleo \u2013ese que a nadie se le puede sustraer\u2013 cuando ven los espect\u00e1culos continuos de quienes son nuestros gu\u00edas, esos que apelan hasta la n\u00e1usea al lugar com\u00fan de que ellos trabajan por y para el ciudadano y, adem\u00e1s, solo atienden a lo que importa y desprecian lo trivial. Y a mi lo que me importa no son sus amores o fobias, sino que volvemos al cole con la incertidumbre de si habr\u00e1 o no maestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vuelta al cole municipal no ha podido ser m\u00e1s abrupta. Como escolares que regresan de mal humor a las aulas despu\u00e9s de un verano de sol, piscina, pueblo, playa o donde narices haya estado cada uno, la han montado. Cruce de palabras y plante en el pleno y r\u00e9plica y contrarr\u00e9plica en los d\u00edas [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/posts\/157"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/posts\/157\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/media?parent=157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/categories?post=157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/lacanaleja\/wp-json\/wp\/v2\/tags?post=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}