{"id":100,"date":"2010-01-20T13:48:00","date_gmt":"2010-01-20T13:48:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=100"},"modified":"2010-01-20T13:48:00","modified_gmt":"2010-01-20T13:48:00","slug":"y-ajena","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2010\/01\/20\/y-ajena\/","title":{"rendered":"\u00bfY LA AJENA?"},"content":{"rendered":"<p> La firma del acuerdo de financiaci\u00f3n auton\u00f3mica es una buena noticia para cerrar 2009. Que el Gobierno y la Junta hayan sellado el pacto (por obra y gracia de unos fondos adicionales de 284 millones de euros para este a\u00f1o) es para felicitarse. Y para felicitar a populares y socialistas. El acuerdo est\u00e1 ah\u00ed. Pero, claro, es para financiaci\u00f3n propia, es decir, para los dineros que las administraciones p\u00fablicas ponen sobre la mesa con el fin de costear los servicios p\u00fablicos, especialmente los esenciales (sanidad, educaci\u00f3n&#8230;). Financiaci\u00f3n propia que sale de los dineros del contribuyente.<br \/>\nSin embargo, y pese a la tranquilidad que deber\u00eda dar un acuerdo de estas caracter\u00edsticas, llega en un momento especialmente intranquilo desde el punto de vista de la financiaci\u00f3n, pero por la ajena, aquella que las entidades bancarias y de ahorro posibilitan para empresas y particulares. Si nos centramos en las cajas, la comunidad lleva un tiempo largo, demasiado largo, contemplando el episodio de las fusiones de cajas. Y se cierra el 2009 con el proceso de esta forma: Caja Espa\u00f1a y Caja Duero, negociando los detalles de c\u00f3mo unirse. Caja de Burgos iniciando una fusi\u00f3n con Caja Canarias, Caja Navarra y Sa Nostra (Baleares). Caja de \u00c1vila y Caja Segovia esperando la llamada de Caja Madrid. Y Cajac\u00edrculo en solitario, pero con la vista puesta en los movimientos del resto.<br \/>\nPreocupante panorama, que s\u00f3lo alivian en parte las dos grandes, Caja Espa\u00f1a y Caja Duero, que bien porque se vean obligadas a entenderse bien porque tengan algo de vocaci\u00f3n autonomista, al menos miran de puertas adentro para, tratando de crear una caja muy s\u00f3lida, optar luego con una posici\u00f3n de m\u00e1s fuerza a negociar con entidades de fuera en el caso de que sea necesario, como parece que lo ser\u00e1 despu\u00e9s de una crisis financiera como la que padecemos ahora mismo.<br \/>\nM\u00e1s dif\u00edcil ante la opini\u00f3n p\u00fablica regional lo van a tener las otras entidades que no han querido tener nada que ver con las cajas de la regi\u00f3n. Por ejemplo, Caja de Burgos opta por unirse a cajas de fuera con una f\u00f3rmula similar a la que le propusieron hace m\u00e1s de un a\u00f1o para juntarse a las cajas de la regi\u00f3n. \u00bfPor qu\u00e9 vale esa f\u00f3rmula ahora y no le serv\u00eda para estar con las cajas de la comunidad? Criticaron que el proceso hace un a\u00f1o estaba politizado porque lo impulsaban PP y PSOE, y ahora se une a una caja (la de Navarra) presidida por el presidente de la comunidad, cargo pol\u00edtico donde los haya. \u00bfEst\u00e1 garantizada la toma de decisiones en Burgos? \u00bfY que el ahorro burgal\u00e9s no se vaya a financiar proyectos canarios?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La firma del acuerdo de financiaci\u00f3n auton\u00f3mica es una buena noticia para cerrar 2009. Que el Gobierno y la Junta hayan sellado el pacto (por obra y gracia de unos fondos adicionales de 284 millones de euros para este a\u00f1o) es para felicitarse. Y para felicitar a populares y socialistas. El acuerdo est\u00e1 ah\u00ed. Pero, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-100","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/100\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}