{"id":123,"date":"2010-08-31T12:39:00","date_gmt":"2010-08-31T12:39:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=123"},"modified":"2010-08-31T12:39:00","modified_gmt":"2010-08-31T12:39:00","slug":"ensayo-general","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2010\/08\/31\/ensayo-general\/","title":{"rendered":"Ensayo general"},"content":{"rendered":"\n<p align=\"justify\">Gobierno regional y PSOE librar\u00e1n una dura batalla en abril por la pol\u00edtica de poblaci\u00f3n<\/p>\n<p align=\"justify\">\n<hr>\n<p> La Semana de Pasi\u00f3n ha sido casi apasionante en la pol\u00edtica regional, aunque sin grandes alharacas, porque la batalla soterrada que est\u00e1n librando desde hace semanas el Gobierno de Herrera y los socialistas por la pol\u00edtica de poblaci\u00f3n, con la que el presidente de la Junta ha decidido marcar el \u00faltimo a\u00f1o de la legislatura, ha sacado a la luz buena parte de la estrategia inmediata de ambos partidos. Ha sido como un ensayo general de lo que viene hasta julio.<br \/>\nEl Gobierno regional dio un golpe de efecto el pasado lunes en sus preparativos para cerrar la Agenda de Poblaci\u00f3n. Desde el Banco de Pensadores (ese grupo de expertos de varios sectores cuya forma de elecci\u00f3n puede seguir siendo discutible, pero cuya selecci\u00f3n ha sido impecable) se organiz\u00f3 una jornada sobre poblaci\u00f3n.<br \/>\nFue invitada la ge\u00f3grafa catalana Anna Cabr\u00e9 i Pla. Esta catedr\u00e1tica de Geograf\u00eda Humana es a las materias sobre poblaci\u00f3n lo que Guillermo de la Dehesa a la econom\u00eda, lo que Jos\u00e9 Luis Sampedro al humanismo o lo que Enrique Rojas a la medicina: una autoridad. La elecci\u00f3n de Anna Cabr\u00e9 no ha sido aleatoria. Desde el Banco de Pensadores se quer\u00eda a alguien cuya voz sobre demograf\u00eda fuese indiscutible para que lo que indicase sirviese en buena medida de ayuda al diagn\u00f3stico y, desde \u00e9ste, a la b\u00fasqueda de soluciones.<br \/>\nAnna Cabr\u00e9 es ahora mismo de las voces m\u00e1s relevantes en Europa en estudios demogr\u00e1ficos. A su licenciatura por la Universidad de Par\u00eds y a su doctorado por la Aut\u00f3noma de Barcelona, le a\u00f1ade haber sido profesora de las universidades de Montreal, Chicago, Sorbona, Nanterre y M\u00e9xico. Cabr\u00e9 i Pla es disc\u00edpula de relevant\u00edsimos dem\u00f3grafos como Louis Henry, Roland Pressat y Alfred Sauvy. Este \u00faltimo fue quien acu\u00f1\u00f3 la expresi\u00f3n &#8220;tercer mundo&#8221; para referirse a los pa\u00edses menos desarrollados de los menos desarrollados, es decir, a los m\u00e1s pobres del planeta, y lleg\u00f3 hasta la ONU, donde dirigi\u00f3 la Comisi\u00f3n de Estad\u00edstica y Poblaci\u00f3n. Con influencias de este calibre, Anna Cabr\u00e9 i Pla es hoy la voz m\u00e1s experta que circula por Europa en materia de poblaci\u00f3n. Su firma est\u00e1 estampada en sesenta proyectos de investigaci\u00f3n y en unas 150 publicaciones sobre la materia.<br \/>\n\u00abLo peor ya ha pasado\u00bb<br \/>\nCon este bagaje, se present\u00f3 el lunes pasado en Valladolid y pronunci\u00f3 esta frase: \u00abLo peor de la despoblaci\u00f3n ha pasado ya en Castilla y Le\u00f3n\u00bb. Y sentenci\u00f3 que lo que ahora ocurra depender\u00e1 de las pol\u00edticas que sea capaz de poner en marcha el Ejecutivo auton\u00f3mico para ofrecer alternativas de empleo.<br \/>\nEl resumen del mensaje que dej\u00f3 es una palabra: optimismo. Optimismo con el que hay que afrontar ahora mismo en Castilla y Le\u00f3n un asunto tan delicado como la poblaci\u00f3n. Claro que, cuando decenas de pueblos de Castilla y Le\u00f3n est\u00e1n abocados al cierre por falta de personal, lo m\u00e1s complicado es ver el futuro demogr\u00e1fico con optimismo. Pero no hay otra. O se ve as\u00ed, o apaga y v\u00e1monos.<br \/>\nPrecisamente \u00e9sa fue la esencia del discurso con el que Herrera present\u00f3 en febrero la Agenda de Poblaci\u00f3n en las Cortes: optimismo. Fue algo como \u00abtan mal no estamos en lo que a poblaci\u00f3n se refiere; hemos ganado habitantes en los \u00faltimos a\u00f1os; otra cosa es que el reparto de ese aumento est\u00e9 extraordinariamente desequilibrado a favor del medio urbano\u00bb. Y aqu\u00ed es donde quiere atacar con su Agenda. Estar\u00e1 presentada antes del d\u00eda 23 de abril, fiesta de la Comunidad. Ma\u00f1ana mismo, el consejero de la Presidencia, al que Juan Vicente Herrera le ha encargado la agenda, empieza la tercera ronda de contactos con el medio centenar de colectivos a los que ha pedido sugerencias y propuestas.<br \/>\nPostura l\u00f3gica<br \/>\n\u00bfY las del PSOE? \u00bfLas aceptar\u00e1 Herrera tambi\u00e9n? En este ensayo general de estrategias, el consejero portavoz ya dej\u00f3 claro que aceptar\u00e1 del PSOE \u00ablo que sea viable\u00bb. \u00d3scar L\u00f3pez no quiere ser ahora c\u00f3mplice de esta agenda, como lo fue en su d\u00eda su antecesor, \u00c1ngel Villalba, de la fracasada primera estrategia de Herrera contra la despoblaci\u00f3n. No s\u00f3lo es l\u00f3gica la postura de L\u00f3pez, sino congruente con sus planteamientos. Cosa distinta es que est\u00e9 acertando en la puesta en escena, que est\u00e1 adoleciendo de falta de credibilidad por, precisamente, la elecci\u00f3n de los actores. El pasado lunes, el PSOE regional se despachaba contra el portavoz de la Junta, redactor y negociador de la Agenda de Poblaci\u00f3n, con una nota de prensa (que firmaba Juli\u00e1n Sim\u00f3n de la Torre, responsable regional de pol\u00edtica municipal), de nada menos que tres folios, en la que dec\u00eda que la postura del consejero, al denominar t\u00f3picos a expresiones como que Castilla y Le\u00f3n se desertiza, es un insulto contra los j\u00f3venes, los vecinos de los municipios, los padres, los mayores, los colectivos sociales, el Estatuto de Autonom\u00eda? S\u00f3lo se libraban del insulto el colegio cardenalicio y la Biblia. Horas despu\u00e9s, el propio L\u00f3pez tildaba de esquizofr\u00e9nica la postura del consejero. \u00a1Qu\u00e9 casualidad! Cuando hace unas semanas De Santiago-Ju\u00e1rez calific\u00f3 de esquizofr\u00e9nico el lenguaje de L\u00f3pez (una cosa aqu\u00ed, otra en Madrid), el l\u00edder socialista le exigi\u00f3 que se disculpase.<br \/>\nBien por la forma (t\u00e9rminos que no le gustan contra \u00e9l), bien por el fondo (que le hagan de portavoces en poblaci\u00f3n dirigentes muy del pasado socialista regional, cuando tiene otros expertos en la materia), el PSOE regional camina ahora mismo en un terreno resbaladizo en el debate sobre la poblaci\u00f3n. En la Moncloa llevan los socialistas seis a\u00f1os y basta mirar las inversiones presupuestarias estatales para saber que a la hora de hablar de desequilibrios territoriales no pueden tirar la primera piedra.  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Gobierno regional y PSOE librar\u00e1n una dura batalla en abril por la pol\u00edtica de poblaci\u00f3n La Semana de Pasi\u00f3n ha sido casi apasionante en la pol\u00edtica regional, aunque sin grandes alharacas, porque la batalla soterrada que est\u00e1n librando desde hace semanas el Gobierno de Herrera y los socialistas por la pol\u00edtica de poblaci\u00f3n, con la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-123","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=123"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/123\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}