{"id":128,"date":"2010-08-31T12:44:00","date_gmt":"2010-08-31T12:44:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=128"},"modified":"2010-08-31T12:44:00","modified_gmt":"2010-08-31T12:44:00","slug":"la-felicidad-la-tierra","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2010\/08\/31\/la-felicidad-la-tierra\/","title":{"rendered":"La felicidad de la tierra"},"content":{"rendered":"\n<p align=\"justify\">J. I. FOCES<\/p>\n<hr>\n<p> El maestro de periodistas Manuel Leguineche escribi\u00f3 entre 1986 y 1999 un diario de campo desde su casa en medio del monte. Lo titul\u00f3 &#8220;La felicidad de la tierra&#8221;. Hay una constante en ese diario, la que conforman las personas. Habla de hombres, de mujeres, de unos y otras en las estaciones del a\u00f1o, de los peque\u00f1os placeres cotidianos? En definitiva, de la vida de la tierra en la que est\u00e1n. Y por la que luchan. Ayer el presidente de la Junta, Juan Vicente Herrera, habl\u00f3 de algo similar en su d\u00e9cimo discurso del D\u00eda de la Comunidad: de las personas que viven en esta tierra, Castilla y Le\u00f3n, y de sus aconteceres.<br \/>\nSi uno vuelve la vista atr\u00e1s esta d\u00e9cada tal d\u00eda como ayer y repasa las intervenciones institucionales de Juan Vicente Herrera, encuentra un elemento que las une: la insistencia en las personas, en los ciudadanos que habitan esta tierra y el protagonismo que \u00e9l les otorga. En el discurso de ayer, ensalz\u00f3 que la comunidad disponga de personas emprendedoras, solidarias y comprometidas (sic), formadas, capaces de construir un futuro sin complejos. Esto se llama potenciar la autoestima colectiva, algo en lo que el presidente insiste \u00faltimamente. Lo hizo el pasado 16 de febrero, cuando present\u00f3 en las Cortes regionales su propuesta para la Agenda de Poblaci\u00f3n y pidi\u00f3 que aprendi\u00e9semos a sacudirnos una serie de t\u00f3picos de los que la madre de todos es \u00e9se que dice que de aqu\u00ed cada vez se marcha m\u00e1s gente. Ayer recalc\u00f3 la necesidad de trabajar para que a Castilla y Le\u00f3n se la conozca y respete por sus ideas y sus obras. Claro que las obras necesitan de personas que las lideren y a estas personas apel\u00f3 el presidente, a los 2,5 millones que vivimos en estas tierras.<br \/>\nDecir algo as\u00ed, pol\u00edticamente puede parecer lo m\u00e1s f\u00e1cil, pero institucionalmente tiene una relevancia enorme por cuanto si los protagonistas de los avances tienen que ser los ciudadanos, los dirigentes que rigen la comunidad quedan en un segundo plano y su papel se limitar\u00eda a arbitrar las condiciones necesarias para que la iniciativa ciudadana salga adelante en las mejores condiciones.<br \/>\nAyer Herrera opt\u00f3 por el pragmatismo frente a la literatura, por la apelaci\u00f3n a lo propio y a los valores del individuo que vive en colectividad frente a los mensajes rimbombantes. En definitiva, por imprimir confianza para expulsar los lamentos. Fue Ortega y Gasset el que dijo aquello de que \u00abla vida, quer\u00e1moslo o no, es una acci\u00f3n que se ejecuta siempre hacia delante\u00bb y el presidente parece que lo ten\u00eda en la cabeza porque habl\u00f3 de que es momento de dar un paso adelante. Pol\u00edticamente estuvo correcto y prefiri\u00f3 moverse dentro de los l\u00edmites de la diplomacia en lo que a la reclamaci\u00f3n ante el Gobierno de Zapatero se refiere. No consta que el presidente tema a la diosa N\u00e9mesis, la diosa de los l\u00edmites, pero quiz\u00e1 el car\u00e1cter del acto pesara en la forma de dirigirse al Gobierno central, sin sobrepasar el l\u00edmite de lo institucional. Para el partido de Zapatero, el PSOE, lanz\u00f3 el mensaje de, m\u00e1s o menos, &#8220;no nos pidan que avancemos en el desarrollo si luego nos escatiman los mecanismos para lograrlo&#8221;, en clara referencia a la cicater\u00eda gubernamental para que Castilla y Le\u00f3n pueda asumir la gesti\u00f3n del agua, fuente segura de riqueza para la colectividad que la tiene.<br \/>\nPero volviendo al conjunto del mensaje, s\u00ed se not\u00f3 la preocupaci\u00f3n por la felicidad de los ciudadanos, a fin de cuentas el \u00fanico objetivo de un pol\u00edtico con responsabilidades: procurar que sus administrados sean felices. Habr\u00e1 que ver si a Herrera este mensaje le dura para cuando dentro de medio a\u00f1o tenga que hacer las listas electorales; por aquello de que elija a quienes procuren conseguir la felicidad de los dem\u00e1s en lugar de la propia. En definitiva, la felicidad de la tierra, que dir\u00eda Leguineche. Una tierra, Castilla y Le\u00f3n, que diecis\u00e9is colectivos pol\u00edticos, sociales, sindicales, empresariales, agrarios y vecinales han asegurado en el Manifiesto de Villalar que \u00abes buena para progresar\u00bb. Y la felicidad tiene mucho que ver con el progreso.  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>J. I. FOCES El maestro de periodistas Manuel Leguineche escribi\u00f3 entre 1986 y 1999 un diario de campo desde su casa en medio del monte. Lo titul\u00f3 &#8220;La felicidad de la tierra&#8221;. Hay una constante en ese diario, la que conforman las personas. Habla de hombres, de mujeres, de unos y otras en las estaciones [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-128","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/128\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}