{"id":131,"date":"2010-08-31T13:56:00","date_gmt":"2010-08-31T13:56:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=131"},"modified":"2010-08-31T13:56:00","modified_gmt":"2010-08-31T13:56:00","slug":"normal","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2010\/08\/31\/normal\/","title":{"rendered":"Normal"},"content":{"rendered":"\n<p align=\"justify\">J. I. FOCES<\/p>\n<hr>\n<p> La entrega de la Medalla de Oro de Castilla y Le\u00f3n a los Reyes en Le\u00f3n demuestra que cuando las cosas normales se hacen con normalidad suelen salir de lo m\u00e1s normal del mundo. Qu\u00e9 diferencia de la visita de ayer de Sus Majestades de la que efectuaron en octubre de 1984. Aquella, por el centenario de la uni\u00f3n ferroviaria de Asturias y Le\u00f3n, se convirti\u00f3 en escenario de una pugna pol\u00edtica leonesista entre la reci\u00e9n creada Junta y el Ayuntamiento de la capital. Seguro que ayer no pudo evitar acordarse de ello el entonces presidente castellano y leon\u00e9s, el socialista Demetrio Madrid, que tuvo que soportar desplantes varios del que era regidor, el popular Juan Morano Masa. Por eso la iniciativa del presidente Herrera de entregar a los Reyes en Le\u00f3n, coincidiendo con el 1.100 aniversario del reino leon\u00e9s, la mayor distinci\u00f3n que tienen los ciudadanos de esta tierra, ha sido acertada. Aporta normalidad a lo que es normal.  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>J. I. FOCES La entrega de la Medalla de Oro de Castilla y Le\u00f3n a los Reyes en Le\u00f3n demuestra que cuando las cosas normales se hacen con normalidad suelen salir de lo m\u00e1s normal del mundo. Qu\u00e9 diferencia de la visita de ayer de Sus Majestades de la que efectuaron en octubre de 1984. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-131","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}