{"id":137,"date":"2010-08-31T14:05:00","date_gmt":"2010-08-31T14:05:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=137"},"modified":"2010-08-31T14:05:00","modified_gmt":"2010-08-31T14:05:00","slug":"pasito-p-alante","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2010\/08\/31\/pasito-p-alante\/","title":{"rendered":"pasito p&#039;alante&#8230;"},"content":{"rendered":"\n<p align=\"justify\">J. I. FOCES<\/p>\n<hr>\n<p> El Gobierno de Zapatero est\u00e1 obligando a los socialistas de toda Espa\u00f1a, da igual el lugar en el que residan, a hacer un papel\u00f3n de tomo y lomo, de los que te doctoran en interpretaci\u00f3n sin haber pasado por la Escuela de Arte Dram\u00e1tico. Cuesta ponerse en el pellejo de un cargo socialista. Qu\u00e9 pensar\u00edan ayer cuando, al incorporarse a sus despachos, se enteraron de que el Ministerio de Econom\u00eda atribu\u00eda a una errata la fecha que imped\u00eda a los ayuntamientos endeudarse durante el a\u00f1o y medio siguiente (ese plazo hab\u00eda comenzado ayer, seg\u00fan el BOE) y la aplazaba al 1 de enero del 2011. Y qu\u00e9 les pasar\u00eda por la cabeza cuando s\u00f3lo unos minutos despu\u00e9s, escasos minutos, trascendi\u00f3 que lo que hab\u00eda sucedido era una rectificaci\u00f3n en toda regla. Frenazo y marcha atr\u00e1s. Ojo, que un frenazo y marcha atr\u00e1s bien explicado no s\u00f3lo no deteriora sino que incluso llega a honrar a quien lo adopta si las razones son de suficiente peso. Pero habiendo escuchado a la ministra restarle importancia a \u00abla errata\u00bb del BOE, la verdad que no era de extra\u00f1ar lo que les pasaba a muchos cargos socialistas, a quienes literalmente seguro que se les enrojecieron los p\u00f3mulos ante semejante desbarajuste de su cada d\u00eda menos idolatrado Zapatero.<br \/>\nOjo, que soy de los que piensan que la &#8220;baraka&#8221; (suerte en \u00e1rabe) del presidente del Gobierno no s\u00f3lo no se ha acabado sino que seguro que le dura lo suficiente para salir airoso de este atolladero. Pero los cargos socialistas asisten at\u00f3nitos a este &#8220;pasito p&#8221;alante, pasito p&#8221;atr\u00e1s&#8221; en las medidas econ\u00f3micas tal y como ayer lo calific\u00f3 el presidente del grupo socialista de Valladolid, \u00d3scar Puente. Lo malo para ellos es que el pasito &#8220;p&#8221;atr\u00e1s&#8221; es un patinazo de los que hacen historia. Y lo saben.  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>J. I. FOCES El Gobierno de Zapatero est\u00e1 obligando a los socialistas de toda Espa\u00f1a, da igual el lugar en el que residan, a hacer un papel\u00f3n de tomo y lomo, de los que te doctoran en interpretaci\u00f3n sin haber pasado por la Escuela de Arte Dram\u00e1tico. Cuesta ponerse en el pellejo de un cargo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-137","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=137"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/137\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}