{"id":148,"date":"2010-08-31T14:17:00","date_gmt":"2010-08-31T14:17:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=148"},"modified":"2010-08-31T14:17:00","modified_gmt":"2010-08-31T14:17:00","slug":"de-atapuerca-rodiezmo","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2010\/08\/31\/de-atapuerca-rodiezmo\/","title":{"rendered":"De Atapuerca a Rodiezmo"},"content":{"rendered":"<p> DE ATAPUERCA A RODIEZMO<\/p>\n<p align=\"justify\">Los socialistas se enfrentan al inicio de curso m\u00e1s duro desde que Zapatero es presidente<\/p>\n<p align=\"justify\">J. I. FOCES<\/p>\n<hr>\n<p> VALLADOLID. Josep Pl\u00e1, uno de los m\u00e1s prodigiosos periodistas que han dado las letras espa\u00f1olas, testigo directo que fue de a\u00f1os clave en la primera mitad del siglo pasado, exclam\u00f3 en una ocasi\u00f3n: \u00abLos socialistas tienen la vida f\u00e1cil, son hombres de suerte. \u00a1Alabado sea Dios!\u00bb. Releyendo ahora sus cr\u00f3nicas, cabe colegir que nunca habr\u00eda escrito algo as\u00ed el insigne maestro de periodistas pensando en los socialistas de Castilla y Le\u00f3n si hubiese sido contempor\u00e1neo nuestro. Es m\u00e1s, si a alg\u00fan dirigente del PSOE castellano y leon\u00e9s se le ocurre releer a Pl\u00e1, mejor que se centre en los escritos de antes de 1933. Fue ese a\u00f1o cuando Josep Pl\u00e1 lanz\u00f3 una de sus sentencias m\u00e1s contundentes: Un pa\u00eds ha de hacer una pol\u00edtica \u00abque sea reflejo de sus posibilidades econ\u00f3micas\u00bb. Y es que es tan actual lo que a\u00f1ad\u00eda a continuaci\u00f3n que perm\u00edtanme que lo traiga a colaci\u00f3n: \u00abAhora estamos haciendo una pol\u00edtica de pa\u00eds rico, a sabiendas de que Espa\u00f1a, excepto en muy pocas zonas, es un pa\u00eds pobre\u00bb.<br \/>\nSerlo no s\u00e9 si lo seremos, pero lo cierto es que para el a\u00f1o pr\u00f3ximo el Presupuesto p\u00fablico auton\u00f3mica va a parecerse mucho al del peor de un a\u00f1o de vacas flacas. No es posible iniciar el curso pol\u00edtico con optimismo. Todav\u00eda retumban en los o\u00eddos las palabras del presidente de la Junta, Juan Vicente Herrera, en el Debate sobre el Estado de la Regi\u00f3n en julio cuando anunci\u00f3 la bajada de las cuentas p\u00fablicas del 2011 en 1.000 millones de euros, \u00a11.000 millones de euros!, respecto a este a\u00f1o. Tuvo la postura diplom\u00e1tica de no mencionar a Zapatero como el culpable del recorte, pero a buen entendedor&#8230;<br \/>\nPese a que ser\u00e1 a\u00f1o electoral, no parece que las urnas vayan a permitir la m\u00e1s m\u00ednima alegr\u00eda financiera. Econom\u00eda de guerra. S\u00ed o s\u00ed. Y ataques mutuos entre populares y socialistas. Declaraciones altisonantes, patadas en la espinilla (metaf\u00f3ricamente hablando, claro) y, especialmente en las filas socialistas, que no se note el drama que se avecina.<br \/>\nParece como si en el seno del partido de Zapatero en Castilla y Le\u00f3n se hubiese ordenado hablar y hablar, cuanto m\u00e1s y cuanto m\u00e1s fuerte contra los populares, mejor. As\u00ed, los focos se centrar\u00e1n -ha debido pensar alg\u00fan iluminado- en lo que dicen o dicen que dicen y no en lo que hacen. Porque si uno se fija en esto segundo es imposible no detenerse en la actuaci\u00f3n de Zapatero en esta su tierra y en las declaraciones de Jos\u00e9 Blanco. Vinoel presidente socialista a Le\u00f3n a principios de agosto para inaugurar un centro de alto rendimiento deportivo y visitar las obras de la estaci\u00f3n provisional del Ave. Aquella visita s\u00ed fue anunciada previamente. Pero el s\u00e1bado 21 sorprendi\u00f3 con un recorrido por los yacimientos de Atapuerca sin anunciarlo. No hubo declaraciones ante la prensa, al contrario que en Le\u00f3n. Claro que la de principios de mes ser\u00e1 recordada por el anuncio que hizo de su candidato a la Alcald\u00eda de Madrid, Jaime Lissavetzky, m\u00e1s que por los mensajes de apoyo a sus compa\u00f1eros castellanos y leoneses.<br \/>\nLa foto, para Herrera<br \/>\nLa visita del pasado d\u00eda 21 ha levantado ampollas en el PSOE regional. Sali\u00f3 ganando Herrera, que se llev\u00f3 la foto con el presidente del Gobierno. Ni un socialista m\u00e1s all\u00ed. Visita cultural, a un lugar emblem\u00e1tico donde los haya, que para eso la investigaci\u00f3n sobre la evoluci\u00f3n humana depende en gran medida de los restos que se encuentren en el yacimiento burgal\u00e9s.<br \/>\nPero lejos de dejar buen sabor de boca en sus filas, lo que hizo fue poner m\u00e1s de manifiesto la ausencia que va a haber el pr\u00f3ximo domingo, 5 de septiembre, en Rodiezmo, en la tradicional fiesta minera a la que Zapatero nunca ha faltado desde que es presidente del Gobierno. Septiembre puede ser un mes dram\u00e1tico para el PSOE, con la convocatoria de huelga general que han lanzado CC. OO. y UGT. Y, por ende, m\u00e1s a\u00fan para el PSOE castellano y leon\u00e9s donde golpean en las sienes los datos de las encuestas que se publicaron en mayo, que dan una ventaja de entre 15 y 25 puntos al PP de Herrera sobre el PSOE de L\u00f3pez.<br \/>\nEn las filas socialistas existe una cada vez mayor sensaci\u00f3n de que Zapatero les ha podido abandonar a su suerte, como si diese por perdida la competici\u00f3n electoral mucho antes incluso de que sea convocada. Por si tienen poco, cada vez que el ministro de Fomento, Jos\u00e9 Blanco, mentor pol\u00edtico de \u00d3scar L\u00f3pez, tiene que sacar un defecto de algo que funciona mal en Espa\u00f1a echa mano de Castilla y Le\u00f3n. Ser\u00e1 recordada durante generaciones esa reciente frase suya de que no se puede mantener un tren en Burgos hacia Madrid con solo seis ocupantes. Y ser\u00e1 recordada tambi\u00e9n la p\u00e9sima gesti\u00f3n medi\u00e1tica que han hecho el Ministerio y el PSOE regional del rescate de obras p\u00fablicas gracias la inyecci\u00f3n estatal de 700 millones de euros.<br \/>\nPor mucho que se lancen a hablar, los dirigentes socialistas son conscientes de que el viaje de Atapuerca a Rodiezmo va a ser muy da\u00f1ino para ellos. El paseo por el yacimiento porque no fue explotado convenientemente desde el punto de vista de la imagen del presidente Zapatero; el segundo, porque su ausencia va a marcar las referencias a la fiesta minera, otrora gran resorte pol\u00edtico del PSOE regional.<br \/>\nSi JosepPl\u00e1 tuviera que escribir ahora no podr\u00eda decir de los socialistas de Castilla y Le\u00f3n que sean hombres de suerte.  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>DE ATAPUERCA A RODIEZMO Los socialistas se enfrentan al inicio de curso m\u00e1s duro desde que Zapatero es presidente J. I. FOCES VALLADOLID. Josep Pl\u00e1, uno de los m\u00e1s prodigiosos periodistas que han dado las letras espa\u00f1olas, testigo directo que fue de a\u00f1os clave en la primera mitad del siglo pasado, exclam\u00f3 en una ocasi\u00f3n: [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-148","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}