{"id":31,"date":"2008-09-21T21:47:14","date_gmt":"2008-09-21T21:47:14","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=31"},"modified":"2008-09-21T21:47:14","modified_gmt":"2008-09-21T21:47:14","slug":"generacion-lopez","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2008\/09\/21\/generacion-lopez\/","title":{"rendered":"Generaci\u00f3n L\u00f3pez"},"content":{"rendered":"<hr>\n<p> Tranquilo, reflexivo, calculador, pacificador, fr\u00edo, cerebral, herm\u00e9tico y trabajador. Y adem\u00e1s, joven, medi\u00e1tico, con pocas concesiones a la frivolidad (pamplinas, ni las justas) y con enorme capacidad dial\u00e9ctica. As\u00ed es el prototipo del nuevo dirigente socialista de Castilla y Le\u00f3n si atendemos a las cualidades que desgran\u00f3 ayer el diputado segoviano \u00d3scar L\u00f3pez en su primera intervenci\u00f3n como flamante l\u00edder.<br \/>\nLos m\u00e1s viejos del lugar se acordar\u00e1n de que despu\u00e9s de aquel congreso de Suresnes (Francia) que consagr\u00f3 a Felipe Gonz\u00e1lez como l\u00edder del PSOE, surgi\u00f3 una clase de dirigentes que se identificaron por su car\u00e1cter de seductores; dominaban el socialismo con propiedades de atracci\u00f3n personal que cautivaban a los auditorios (Felipe, Guerra, Solchaga&#8230;). Otros elud\u00edan la seducci\u00f3n como arma de contacto y prefer\u00edan el convencimiento (Generaci\u00f3n Almunia, Borrell&#8230;). \u00d3scar L\u00f3pez m\u00e1s parece de los primeros que de los segundos.<br \/>\nSi hubiera que definir con una expresi\u00f3n castiza esa intervenci\u00f3n, bien podr\u00eda ser calificada como &#8220;la de los sartenazos&#8221;: los que dio a diestro y siniestro a las generaciones de dirigentes socialistas que se han pasado ya m\u00e1s de dos d\u00e9cadas lanz\u00e1ndose cuchillos, reparti\u00e9ndose cargos y acomod\u00e1ndose en la oposici\u00f3n. Y es que algunos socialistas (lo grave es que no se averg\u00fcenzan de ello) est\u00e1n muy c\u00f3modos en la oposici\u00f3n regional, han cobrado y cobran m\u00e1s que un consejero, van en coche oficial, tienen gabinete&#8230; Mover a todos estos (que a\u00fan hay bastantes) le va a costar a L\u00f3pez dios y ayuda. Pero ya lo dej\u00f3 claro el l\u00edder L\u00f3pez: esencias, todas; pero a modernizarse y a trabajar por la gente.<br \/>\nAyer, en el Auditorio de la Feria de Valladolid, cada vez que L\u00f3pez lanzaba un mensaje del tipo \u00abno sois socialistas para estar encerrados en las sedes repartiendo cargos\u00bb o \u00abun socialista de raza prefiere trabajar sin descanso en el gobierno a descansar del trabajo en la oposici\u00f3n\u00bb, se o\u00eda en el auditorio un \u00abs\u00ed, se\u00f1or\u00bb o \u00abcorrecto, di que s\u00ed\u00bb de delegados a los que les llegaba el contagio de las palabras de L\u00f3pez. Y es que el de L\u00f3pez es un lenguaje nuevo en el PSOE regional; a alguno ayer seguro que le pareci\u00f3 que le hablaba en ingl\u00e9s, porque las palabras de L\u00f3pez van a ser ininteligibles para una generaci\u00f3n de dirigentes que ha llevado al PSOE a la desidia auton\u00f3mica en la que se encuentra. Pero L\u00f3pez sabe que si quiere convencer a la sociedad, antes ha de ganarse el respeto y el convencimiento dentro del PSOE. Ayer empez\u00f3 a hacerlo. Ha nacido la Generaci\u00f3n L\u00f3pez.<br \/>\nblogs.nortecastila.es\/laespita <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tranquilo, reflexivo, calculador, pacificador, fr\u00edo, cerebral, herm\u00e9tico y trabajador. Y adem\u00e1s, joven, medi\u00e1tico, con pocas concesiones a la frivolidad (pamplinas, ni las justas) y con enorme capacidad dial\u00e9ctica. As\u00ed es el prototipo del nuevo dirigente socialista de Castilla y Le\u00f3n si atendemos a las cualidades que desgran\u00f3 ayer el diputado segoviano \u00d3scar L\u00f3pez en su [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-31","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}