{"id":42,"date":"2008-12-02T22:35:41","date_gmt":"2008-12-02T22:35:41","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=42"},"modified":"2008-12-02T22:35:41","modified_gmt":"2008-12-02T22:35:41","slug":"los-acebes-ayudan-lopez","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2008\/12\/02\/los-acebes-ayudan-lopez\/","title":{"rendered":"Los de Acebes ayudan a L\u00f3pez"},"content":{"rendered":"<table class=\"resultado-imagenes\" border=\"0\" cellpadding=\"0\" cellspacing=\"0\" width=\"96%\">\n<tbody>\n<tr>\n<td class=\"resultado-datos\" rowspan=\"2\" valign=\"top\"><strong><br \/>\n                            <\/strong><\/td>\n<td colspan=\"2\" rowspan=\"2\" class=\"resultado-datos\" height=\"40\">\n<hr>\n<p>Ya est\u00e1. El jovenc\u00edsimo l\u00edder socialista regional, \u00d3scar L\u00f3pez, pasa al ataque. Por si alguno se cre\u00eda que la luna de miel pol\u00edtica entre \u00e9l y Herrera, a cuenta sobre todo de las cajas, iba a durar una eternidad, se ha equivocado. L\u00f3pez ha venido para hacer oposici\u00f3n de las de verdad y, miren ustedes por d\u00f3nde, nos encontramos con que en el granero del granero del PP en la regi\u00f3n, \u00c1vila, va a librarse una interesant\u00edsima batalla. No se confundan: no es porque \u00e9sta sea la provincia del &#8220;n\u00famero dos&#8221; de L\u00f3pez, el abulense Pedro Jos\u00e9 Mu\u00f1oz; que va, que va. Es porque en \u00c1vila se acaban de quedar al desnudo las verg\u00fcenzas del Sacyl, a cuenta de la falta de onc\u00f3logos. Tanto ha sido el descalabro que a Herrera no le ha quedado m\u00e1s remedio que pedir perd\u00f3n. Pero el perd\u00f3n no cura c\u00e1nceres y \u00d3scar L\u00f3pez ha sabido ponerse a la cabeza de las protestas, aunque en sus cuentas no estaba tener como aliados a los compa\u00f1eros del otrora mandam\u00e1s del PP, \u00c1ngel Acebes. Porque, \u00bfrecuerda alguien que hayan salido los dirigentes abulenses del PP a exigir a Herrera soluciones para las carencias sanitarias de \u00c1vila? Al menos, \u00bfrecuerda alguien que lo hayan hecho con la misma intensidad, cabreo, ah\u00ednco y empe\u00f1o que pusieron para oponerse a los planes de Herrera de unir las inversiones de las cajas?<br \/>\nSoy de los que opina que el socialista \u00d3scar L\u00f3pez ha llegado a esta regi\u00f3n con ese don especial que los \u00e1rabes llaman &#8220;baraka&#8221;, suerte de suertes, en castellano claro. Pero era imposible imaginar que esa &#8220;baraka&#8221; iba a incluir a aliados como los del PP abulense, que con su tan despegada forma de actuar en la crisis de los onc\u00f3logos han demostrado que, al menos en sus dominios abulenses -nunca una muralla fue tan ilustrativa del aislamiento pol\u00edtico de algunos- empieza a erosionarse la imagen del partido gobernante en la regi\u00f3n, precisamente en una de las dos prioridades del ciudadano: el cuidado de la salud.<br \/>\nblogs.nortecastilla.es\/laespita<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1. El jovenc\u00edsimo l\u00edder socialista regional, \u00d3scar L\u00f3pez, pasa al ataque. Por si alguno se cre\u00eda que la luna de miel pol\u00edtica entre \u00e9l y Herrera, a cuenta sobre todo de las cajas, iba a durar una eternidad, se ha equivocado. L\u00f3pez ha venido para hacer oposici\u00f3n de las de verdad y, miren ustedes [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-42","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}