{"id":43,"date":"2008-12-02T22:37:07","date_gmt":"2008-12-02T22:37:07","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=43"},"modified":"2008-12-02T22:37:07","modified_gmt":"2008-12-02T22:37:07","slug":"luz-gas","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2008\/12\/02\/luz-gas\/","title":{"rendered":"Luz de gas"},"content":{"rendered":"<p>La \u00e9lite de la \u00e9lite econ\u00f3mica y empresarial consigui\u00f3 reunir ayer Caja de Burgos, junto a Cecale y las C\u00e1maras de Comercio, en Valladolid por segundo a\u00f1o consecutivo. El encuentro estaba previsto que lo abriese el presidente de la Junta, Juan Vicente Herrera, quien se caracteriza por hacer visibles sus afectos, por dejar constancia de sus respaldos, por que consten las iniciativas que apoya y por que trascienda que el apoyo presidencial a un proyecto es un aval para quien lo pone en marcha.<br \/>\nDe ah\u00ed que cuando quiere que una ausencia suya se note, vaya si se nota. Y ayer en la apertura del II Encuentro ForoBurgos Econom\u00eda y Empresa, que reuni\u00f3 a la \u00e9lite de la \u00e9lite de este sector en la comunidad, Herrera quiso que se notara su ausencia. Vaya si se not\u00f3. El mensaje, s\u00f3lo uno: Empieza a aplicar luz de gas (hace que trascienda su malestar, que cale que est\u00e1 enfadado, precisamente, por desplantes como el de ayer) a las entidades de ahorro y a algunos sectores del empresariado.<br \/>\nMuy molesto tiene que estar Herrera con cajas y empresarios para haber cancelado su asistencia al foro de ayer. Mucho. Pero, dada esa reacci\u00f3n, cabe cuestionar el instrumento pedag\u00f3gico  que han utilizado el presidente y el socialista L\u00f3pez para trasladar a las cajas su plan para unir negocios e inversiones de estas entidades. En conversaciones privadas no hay dirigente econ\u00f3mico, pol\u00edtico o sindical que no alerte de los nubarrones que est\u00e1n encima del sistema financiero regional. Incluso recalcan que no es que lo digan ellos por que s\u00ed, sino que esta es palabra de la autoridad monetaria nacional. Entonces, si detr\u00e1s de este acuerdo para crear Grupo Cajas Castilla y Le\u00f3n est\u00e1 el Banco de Espa\u00f1a, \u00bfno deber\u00edan Herrera y L\u00f3pez haber echado mano de este argumento desde el inicio?<br \/>\nLas cosas se han torcido. Mucha paciencia van a tener que mostrar Herrera y L\u00f3pez para aguantar este envite. Que lo es; si no, Herrera no habr\u00eda aplicado luz de gas.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La \u00e9lite de la \u00e9lite econ\u00f3mica y empresarial consigui\u00f3 reunir ayer Caja de Burgos, junto a Cecale y las C\u00e1maras de Comercio, en Valladolid por segundo a\u00f1o consecutivo. El encuentro estaba previsto que lo abriese el presidente de la Junta, Juan Vicente Herrera, quien se caracteriza por hacer visibles sus afectos, por dejar constancia de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-43","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/43\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=43"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}