{"id":46,"date":"2008-12-22T10:44:41","date_gmt":"2008-12-22T10:44:41","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=46"},"modified":"2008-12-22T10:44:41","modified_gmt":"2008-12-22T10:44:41","slug":"de-gran-caja-cajon-desastre","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2008\/12\/22\/de-gran-caja-cajon-desastre\/","title":{"rendered":"De gran caja a caj\u00f3n desastre"},"content":{"rendered":"<p>Esto parece un cl\u00e1sico Barcelona-Madrid en lo que a calentar los d\u00edas previos del partido se refiere. M\u00e1s presi\u00f3n no cabe cuando faltan 72 horas para la tensa reuni\u00f3n de la Federaci\u00f3n de Cajas. Las dos partes -el PP y el PSOE, por un lado, y los m\u00e1ximos dirigentes de las cajas, por otro- est\u00e1n dando muestras evidentes de un pulso de los de verdad.<br \/>\nPero al paso que van unos y otros, sobre todo los dos grandes partidos, parece que alguien no est\u00e1 midiendo bien las consecuencias de determinadas decisiones, que llevan camino de terminar en lugar de en una gran caja en un caj\u00f3n&#8230; desastre (todo junto). Y a quien ha apostado en esto a una carta a favor de Herrera, \u00d3scar L\u00f3pez, le empiezan a crecer problemas de un importante nivel. El comunicado de ayer elaborado por la ejecutiva del PSOE de Salamanca es de los que marcan un antes y un despu\u00e9s. Porque, hasta ahora, L\u00f3pez hab\u00eda tenido como \u00fanica voz en contra en su partido al alcalde de Le\u00f3n. Pero lo de Salamanca no es una declaraci\u00f3n individual, es una decisi\u00f3n colegiada de la direcci\u00f3n provincial en contra del acuerdo PP-PSOE en el \u00e1mbito regional para unir a las cajas de ahorro. En esto Herrera y L\u00f3pez est\u00e1n empatados, porque al primero le sigue la fuerte contestaci\u00f3n interna en \u00c1vila. Nadie hasta ahora en el PSOE hab\u00eda previsto una andanada como la que ayer le lleg\u00f3 a la ejecutiva regional socialista desde Salamanca. Una afrenta a quien es el principal interlocutor del PP para las cajas, el abulense Pedro Mu\u00f1oz, n\u00famero dos de L\u00f3pez.<br \/>\nblogs.nortecastilla.es\/laespita  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Esto parece un cl\u00e1sico Barcelona-Madrid en lo que a calentar los d\u00edas previos del partido se refiere. M\u00e1s presi\u00f3n no cabe cuando faltan 72 horas para la tensa reuni\u00f3n de la Federaci\u00f3n de Cajas. Las dos partes -el PP y el PSOE, por un lado, y los m\u00e1ximos dirigentes de las cajas, por otro- est\u00e1n [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-46","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}