{"id":47,"date":"2008-12-30T22:28:53","date_gmt":"2008-12-30T22:28:53","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=47"},"modified":"2008-12-30T22:28:53","modified_gmt":"2008-12-30T22:28:53","slug":"buena-noticia-medias","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2008\/12\/30\/buena-noticia-medias\/","title":{"rendered":"Buena noticia, a medias"},"content":{"rendered":"<p> En un a\u00f1o en el que el pesimismo ha marcado la actualidad m\u00e1s pegada al ciudadano, sobre todo por la crisis econ\u00f3mica, resulta casi agradable escuchar que la poblaci\u00f3n sigue creciendo y, que adem\u00e1s, lo hace a un ritmo notable, con casi 29.000 personas m\u00e1s. Tiempo habr\u00e1 de analizar con detalle las causas, aunque no hay que ser un estadista para saber que la inmigraci\u00f3n y el crecimiento vegetativo, que en los dos \u00faltimos a\u00f1os ha sido positivo, justifican ese aumento del n\u00famero de habitantes.<br \/>\nSin embargo, ese aumento no es ni mucho menos uniforme y tiene en el apartado de n\u00fameros rojos a la provincia de Zamora. Es el ejemplo m\u00e1s palpable de que en la Espa\u00f1a de dos velocidades (las comunidades ricas, las comunidades pobres) hay otras dos velocidades (las provincias ricas en comunidades pobres y las provincias pobres en comunidades pobres, que es lo que a efectos del censo de habitantes es ahora mismo Zamora).<br \/>\nCon datos que invitan al optimismo (28.913 habitantes m\u00e1s son muchos) es hasta de agradecer que ayer el consejero portavoz de la Junta, Jos\u00e9 Antonio de Santiago-Ju\u00e1rez, no hiciera un discurso triunfalista. Lo ten\u00eda f\u00e1cil, pero prefiri\u00f3 mantenerse en un terreno de euforia contenida (\u00abalgo tendr\u00e1n que ver las pol\u00edticas desarrolladas en los \u00faltimos a\u00f1os desde la Junta\u00bb, dijo). No es para menos. Si uno mira donde m\u00e1s crece la poblaci\u00f3n es en Burgos, Valladolid, Segovia y \u00c1vila. Estas dos \u00faltimas, pegadas a Madrid; las dos primeras, en el eje industrial puntero.<br \/>\nPero el censo deja un mal sabor de boca: Sigue habiendo una Castilla y Le\u00f3n de primera (esas cuatro provincias son el reflejo m\u00e1s fiel) y otra de segunda, en la que Zamora representa el ejemplo de c\u00f3mo han fracasado las pol\u00edticas contra la despoblaci\u00f3n. Por eso, la buena noticia lo es s\u00f3lo a medias.<br \/>\nblogs.nortecastilla.es\/laespita <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En un a\u00f1o en el que el pesimismo ha marcado la actualidad m\u00e1s pegada al ciudadano, sobre todo por la crisis econ\u00f3mica, resulta casi agradable escuchar que la poblaci\u00f3n sigue creciendo y, que adem\u00e1s, lo hace a un ritmo notable, con casi 29.000 personas m\u00e1s. Tiempo habr\u00e1 de analizar con detalle las causas, aunque no [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-47","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}