{"id":67,"date":"2009-05-15T12:13:00","date_gmt":"2009-05-15T12:13:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=67"},"modified":"2009-05-15T12:13:00","modified_gmt":"2009-05-15T12:13:00","slug":"optimismo-ya-era-hora","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2009\/05\/15\/optimismo-ya-era-hora\/","title":{"rendered":"Optimismo, ya era hora"},"content":{"rendered":"<br \/>\n<hr>\n<p> Herrera escribi\u00f3 ayer en \u00c1vila una de las mejores piezas de su oratoria pol\u00edtica desde que es presidente de la Junta. Por el mensaje, sobre todo por el mensaje. Y, claro, por c\u00f3mo lo expres\u00f3: Lenguaje llano, sintaxis sencilla y entonaci\u00f3n apropiada para un acto en el que, por regla general, se suele lanzar m\u00e1s filosof\u00eda que concreciones. Pero ayer fue distinto. Herrera eludi\u00f3 cualquier atisbo de pol\u00e9mica con el Gobierno de la naci\u00f3n. Eso s\u00ed, critic\u00f3 -de buenas maneras, claro- que Zapatero y su equipo econ\u00f3mico no hayan puesto orden en el sinf\u00edn de iniciativas auton\u00f3micas contra la crisis. Pero nada m\u00e1s de cr\u00edtica en un momento en el que con las concesiones del Ejecutivo central al catal\u00e1n Herrera, y su consejera de Hacienda escribir\u00edan una biblia.<br \/>\nSi por la estructura el discurso es de los de guardar y releer, por el tono m\u00e1s a\u00fan. Porque llevamos oyendo hablar de crisis tanto que uno no sabe si el apocalipsis est\u00e1 tan cerca que hay que empezar a hacer prop\u00f3sito de la enmienda. Y ayer Herrera se solt\u00f3 con una inyecci\u00f3n de optimismo que se podr\u00eda resumir en una idea: \u00abSe\u00f1ores, que s\u00ed, que vamos a salir de la crisis; y lo vamos a hacer todos juntos. No hay otra manera\u00bb. Hac\u00eda falta escuchar esto en un d\u00eda tan dado a cargar las tintas con grandes citas literarias. Y lo que hizo ayer el presidente fue recurrir s\u00f3lo a una, de Miguel Delibes, flamante cuarta Medalla de Oro de Castilla y Le\u00f3n. Herrera ech\u00f3 mano de una frase del autor de &#8220;El Hereje&#8221; para reafirmar m\u00e1s su optimismo: \u00abCastilla y Le\u00f3n soportar\u00e1 baches, pero siempre ir\u00e1 a m\u00e1s\u00bb. Hace unos d\u00edas, en el Foro Econ\u00f3mico de EL NORTE, el ex ministro Eduardo Serra dijo que lo mejor en una situaci\u00f3n de crisis es que los gobernantes digan la verdad. Ayer, Herrera no ocult\u00f3 en ning\u00fan momento que la econom\u00eda est\u00e1 mal, muy mal. Pero lo acompa\u00f1\u00f3 de un mensaje lo suficientemente positivo como para pensar que es posible la recuperaci\u00f3n. Ya era hora de escucharlo en un acto tan solemne.<br \/>\nblogs.nortecastilla.es\/laespita  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Herrera escribi\u00f3 ayer en \u00c1vila una de las mejores piezas de su oratoria pol\u00edtica desde que es presidente de la Junta. Por el mensaje, sobre todo por el mensaje. Y, claro, por c\u00f3mo lo expres\u00f3: Lenguaje llano, sintaxis sencilla y entonaci\u00f3n apropiada para un acto en el que, por regla general, se suele lanzar m\u00e1s [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-67","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=67"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/67\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=67"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=67"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}