{"id":69,"date":"2009-05-15T12:14:00","date_gmt":"2009-05-15T12:14:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/laespita\/?p=69"},"modified":"2009-05-15T12:14:00","modified_gmt":"2009-05-15T12:14:00","slug":"dos-anos-y-crisis-despues","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/laespita\/2009\/05\/15\/dos-anos-y-crisis-despues\/","title":{"rendered":"Dos a\u00f1os y una crisis despu\u00e9s &#8230;"},"content":{"rendered":"<br \/>\n<hr>\n<p> El relevo de la portavoz en la Diputaci\u00f3n es el culmen de otro conflicto, uno m\u00e1s, de esos que a los socialistas les gusta estirar y estirar a base de poner cortinas a las situaciones pol\u00e9micas. Lo de ayer no es m\u00e1s que el intento de solucionar un conflicto con dos a\u00f1os de retraso. Cuando se hacen las cosas as\u00ed, lo que ocurre al final es que se acumula tiempo y lo que era un problema se convierte en crisis.<br \/>\nHace dos a\u00f1os los diputados provinciales socialistas se inclinaron por Juan Jos\u00e9 Zancada como portavoz; pero la direcci\u00f3n socialista, encabezada entonces por Jorge F\u00e9lix Alonso, oblig\u00f3 a que siguiera de portavoz Ana V\u00e1zquez. Dos a\u00f1os despu\u00e9s, al PSOE no le ha quedado m\u00e1s remedio que quitarla del medio (llamemos a las cosas por su nombre, porque esto es una destituci\u00f3n en toda regla) y situar en el puesto a quien ya hab\u00edan elegido los diputados hace dos a\u00f1os.<br \/>\n\u00bfQu\u00e9 ha ganado el PSOE con esto? Nada de nada. \u00bfQu\u00e9 ha perdido? Mucho. Entre otras cosas, credibilidad y dos a\u00f1os para no s\u00f3lo hacer oposici\u00f3n, que es lo m\u00e1s f\u00e1cil de la pol\u00edtica, sino para presentar alternativas, que eso s\u00ed que es complicado. \u00bfConoce alguien en estos dos a\u00f1os pasados alguna propuesta sonora para el desarrollo provincial, de esas que dejan huella, que haya salido de las filas el PSOE? El nuevo secretario provincial socialista, Mario Bedera, tiene ahora una oportunidad de oro para demostrar que sabe sacar al PSOE de las p\u00e1ginas de sucesos y devolverlo a las de pol\u00edtica.<br \/>\nblogs.nortecastilla.es\/laespita  <\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El relevo de la portavoz en la Diputaci\u00f3n es el culmen de otro conflicto, uno m\u00e1s, de esos que a los socialistas les gusta estirar y estirar a base de poner cortinas a las situaciones pol\u00e9micas. Lo de ayer no es m\u00e1s que el intento de solucionar un conflicto con dos a\u00f1os de retraso. Cuando [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-69","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/posts\/69\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/media?parent=69"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/categories?post=69"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/laespita\/wp-json\/wp\/v2\/tags?post=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}