{"id":54,"date":"2013-09-25T09:00:20","date_gmt":"2013-09-25T09:00:20","guid":{"rendered":"http:\/\/blogs.grada360.com\/los-5-momentos-de-nuestros-emigrantes\/?p=54"},"modified":"2013-09-25T09:00:20","modified_gmt":"2013-09-25T09:00:20","slug":"desde-llorente-a-fran-merida","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/2013\/09\/25\/desde-llorente-a-fran-merida\/","title":{"rendered":"Desde Llorente a Fran M\u00e9rida"},"content":{"rendered":"<p><!--:es-->1. El fin de semana de los nuestros emigrantes ya tiene el nombre propio que todos est\u00e1bamos esperando. <strong>Fernando Llorente, delantero de la Juventus<\/strong> tuvo su oportunidad y la aprovech\u00f3. El delantero riojano parec\u00eda condenado al ostracismo pero Conte le dio minutos ante el Hellas Verona y Llorente anot\u00f3 el segundo gol del partido.<\/p>\n<p><!--:--><!--:en--><\/p>\n<p>\n<!--:--><!--more--><!--:es--><\/p>\n<p>2. El partidazo de la Premier tambi\u00e9n tuvo sabor espa\u00f1ol. Manchester City y Manchester United enfrentaban a<strong> Negredo, Navas y Javi Garc\u00eda a David De Gea<\/strong>. El protagonismo fue para el conjunto &#8216;citizen&#8217; que gole\u00f3 a sus vecinos con dos asistencias espa\u00f1olas. La de Negredo al Kun y la de Navas a Nasry para cerrar el partido.<\/p>\n<p>3. Sin salir de la Premier hay que irse a Selhurst Park, en Londres, para ver el <strong>Swansea-Crystal Palace<\/strong>. No tuvo bastante <strong>Michu<\/strong> con apuntillar al Valencia en Europa League que apenas tard\u00f3 dos minutos en abrir el marcador ante un serio candidato al descenso.<\/p>\n<p>4. En Brasil esta nuestro cuarto emigrante. <strong>Fran M\u00e9rida<\/strong>, la eterna promesa del f\u00fatbol espa\u00f1ol hace patria en el <strong>Atl\u00e9tico Paranaense<\/strong> y lider\u00f3 la remontada de su equipo ante el Flamengo anotando el 2-1 de un partido que acabar\u00edan ganando 2-4.<\/p>\n<p>5. <strong>Ra\u00fal Albiol<\/strong>. El 33 a la espalda y San Paolo a los pies de un equipo que opta sin discusi\u00f3n a luchar por el Calcio despu\u00e9s de importante visctoria ante el Milan. El primer gol de Britos lleg\u00f3 tras una asistencia de cabeza de Albiol dentro del \u00e1rea.<br \/>\n<!--:--><!--:en--><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. El fin de semana de los nuestros emigrantes ya tiene el nombre propio que todos est\u00e1bamos esperando. Fernando Llorente, delantero de la Juventus tuvo su oportunidad y la aprovech\u00f3. El delantero riojano parec\u00eda condenado al ostracismo pero Conte le dio minutos ante el Hellas Verona y Llorente anot\u00f3 el segundo gol del partido.<\/p>\n","protected":false},"author":16779,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[14,20,24,26],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/posts\/54"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/users\/16779"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/posts\/54\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/media?parent=54"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/categories?post=54"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/los-5-momentos-de-nuestros-emigrantes\/wp-json\/wp\/v2\/tags?post=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}