{"id":17,"date":"2010-02-09T17:47:00","date_gmt":"2010-02-09T17:47:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/pasameelmando\/?p=17"},"modified":"2010-02-09T17:47:00","modified_gmt":"2010-02-09T17:47:00","slug":"lo-mejor-y-peor-perdidos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/2010\/02\/09\/lo-mejor-y-peor-perdidos\/","title":{"rendered":"Lo mejor y lo peor de &#039;Perdidos&#039;"},"content":{"rendered":"<p>A las 21:30 Fox y a las 22:15 Cuatro estrenan, en espa\u00f1ol, la sexta y \u00faltima temporada de <a id=\"link_0\" title=\"http:\/\/nortecastilla.laguiatv.com\/serie\/ficha\/Perdidos\/144079\" href=\"http:\/\/nortecastilla.laguiatv.com\/serie\/ficha\/Perdidos\/144079\" rel=\"nofollow external\" target=\"_blank\">Perdidos<\/a>. En los proleg\u00f3menos de la emisi\u00f3n bien vale llevar a cabo un peque\u00f1o recordatorio de lo m\u00e1s destacado de los 103 cap\u00edtulos precedentes.<\/p>\n<p><img id=\"img_0\" class=\"imgcen\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\" alt=\"\" \/><!--more--><\/p>\n<h4><span style=\"color: #3366ff;\"><span style=\"color: #00cccc;\">&#8211; Mejor escena:<\/span> <\/span><\/h4>\n<p>En \u2018Tricia Tanaka ha muerto\u2019 (3&#215;14) Hurley se encuentra una <strong>furgoneta de la Iniciativa Dharma<\/strong>. Con la ayuda de Charlie, Sawyer y Jin consiguen hacerla funcionar, en una misi\u00f3n un tanto suicida. Yo me sent\u00eda uno m\u00e1s de esa furgoneta, junto a Hurley y Charlie.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Mejor temporada: <\/span><\/h4>\n<p>Sin dudarlo <strong>la primera<\/strong>, de principio a fin. Desde el primer cap\u00edtulo, que presenta toda la historia, hasta el \u00faltimo que termina con todos mirando hacia la luz que se ha encendido bajo la escotilla. \u00a1\u00a1Nunca he tenido tantas ganas de ver el siguiente cap\u00edtulo!!<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Peor temporada: <\/span><\/h4>\n<p><strong>\u00bfEs que hay alguna mala?<\/strong> Si tengo que elegir me quedo con la tercera, aunque siento que me traiciono a mi mismo eligiendo.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Personaje preferido: <\/span><\/h4>\n<p><strong>John Locke<\/strong> representa el eje sobre el que una y otra vez la historia vuelve a girar. Es quien encarna los valores de la isla, el que mantiene a los dem\u00e1s en consonancia con ella y el alter ego perfecto para Jack, ya lo dice el t\u00edtulo de uno de los cap\u00edtulos, \u2018Hombre de ciencia, hombre de fe\u2019.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Personaje que desear\u00edas que muriera (o que te alegras de que ya lo haya hecho): <\/span><\/h4>\n<p>Acab\u00f3 como un h\u00e9roe y siempre estuvo condicionado por Walt y los tejemanejes de Benjamin Linus <strong>pero nunca me cay\u00f3 bien Michael<\/strong>. En fin, alguno ten\u00eda que ser el peor.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; La revelaci\u00f3n m\u00e1s impactante:<\/span><\/h4>\n<p>Desmond reconstruye lo que ocurri\u00f3 cuando el avi\u00f3n cay\u00f3 en la isla y <strong>la raz\u00f3n de que eso ocurriera<\/strong>. Concretamente en la segunda parte de \u2018Vivir juntos, morir solos\u2019, el 2&#215;24<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Mejor pareja: <\/span><\/h4>\n<p><strong>Desmond y Penny<\/strong>. Amor por encima de todo, \u00e9l realiza un viaje en barco alrededor del mundo para demostrar que es un buen hombre, ella lleva a cabo una b\u00fasqueda incansable por encontrar a su desaparecida pareja, una lucha con \u00bffinal feliz?<br \/>\n<span style=\"color: #00cccc;\"><br \/>\n<\/span><\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Peor pareja: <\/span><\/h4>\n<p><strong>Nikki y Paulo<\/strong>, esa pareja de guaperas que duraron tan solo siete cap\u00edtulos (hasta el 3&#215;14 &#8216;Revelaci\u00f3n&#8217;). En fin, pintaban poco en la serie, incluso los guionistas reconocen que se los &#8220;cargaron&#8221; porque no gustaban al p\u00fablico.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Mejor flashback: <\/span><\/h4>\n<p>Me quedo con una extra\u00f1a mezcla de flashbacks, flashforwards y realidades paralelas, el capitulazo de \u2018<strong>La Constante<\/strong>\u2019 (4&#215;05). Uno de los mejores de la serie, sin dudarlo.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Peor flashback: <\/span><\/h4>\n<p>Aqu\u00ed s\u00ed que <strong>me niego a elegir<\/strong>. Tal vez los de Hurley sean los menos jugosos porque carecen de la tensi\u00f3n emocional de otros personajes, pero son tan buenos como el resto.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; Qu\u00e9 da m\u00e1s miedo: humo negro, oso polar o Benjamin Linus: <\/span><\/h4>\n<p><strong>Linus<\/strong>, sin dudarlo. El humo y el oso te matan pero Ben te maneja a su gusto, es lo peor.<\/p>\n<h4><span style=\"color: #00cccc;\">&#8211; La gran inc\u00f3gnita: <\/span><\/h4>\n<p><strong>\u00bfQu\u00e9 es la isla?<\/strong>, en fin, la clave del asunto.<\/p>\n<p>J. A. PARDAL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A las 21:30 Fox y a las 22:15 Cuatro estrenan, en espa\u00f1ol, la sexta y \u00faltima temporada de Perdidos. En los proleg\u00f3menos de la emisi\u00f3n bien vale llevar a cabo un peque\u00f1o recordatorio de lo m\u00e1s destacado de los 103 cap\u00edtulos precedentes.<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/17"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/17\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/media?parent=17"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/categories?post=17"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/tags?post=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}