{"id":21,"date":"2010-02-24T10:07:00","date_gmt":"2010-02-24T10:07:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/pasameelmando\/?p=21"},"modified":"2010-02-24T10:07:00","modified_gmt":"2010-02-24T10:07:00","slug":"perdidos-lost-6x04","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/2010\/02\/24\/perdidos-lost-6x04\/","title":{"rendered":"Perdidos (Lost) 6&#215;04"},"content":{"rendered":"<p>Recuperamos el nivel de los primeros cap\u00edtulos despu\u00e9s del sos\u00edsimo 6&#215;03 y su protagonista Kate. En este episodio se desvelas nuevas cosas y se despiertan varias preguntas. Si en el anterior, no ve\u00edamos a Locke, en este no vemos a los del templo pero no importa. Locke (o quien quiera que sea) es el protagonista y eso es un tanto a favor, de hecho, es el principal tanto a favor.<\/p>\n<p align=\"center\"><em>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; SPOILERS &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/em><\/p>\n<p><strong>GRANDES MISTERIOS ISLE\u00d1OS<\/strong><\/p>\n<p><strong>1.- Locke.<\/strong><\/p>\n<p align=\"center\"><img loading=\"lazy\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\" alt=\"\" width=\"500\" height=\"271\" \/><\/p>\n<p>\u00bfQui\u00e9n demonios es? El cap\u00edtulo comienza con un recorrido subjetivo desde el punto de vista del <strong>humo negro<\/strong> recorriendo los <strong>antiguos barracones de Dharma<\/strong>. Sale a la selva, se detiene delante de un cuchillo y toma la forma de Locke. Entondes libera a Richard al que tiene colgado de un \u00e1rbol como un <strong>saco de patatas<\/strong>.<!--more--><\/p>\n<p>Esta bastante claro que Locke est\u00e1 muerto. Ben, Sun, Lapidus e Ilana lo entierra, con minifuneral incluido as\u00ed que Locke no es Locke, es el humo negro, que a su vez puede tomar otras formas, por eso, seguramente aparece tanta gente muerta en la Isla. Locke va a buscar a Sawyer y Sawyer aunque sabe que no es Locke accede a ir con \u00e9l ya que le promete responder a la pregunta m\u00e1s importante <strong>\u00bfPor qu\u00e9 est\u00e1 en la Isla?<\/strong>.<\/p>\n<p>Al parecer, el humo lleva all\u00ed antes de que el vuelo de Oceanic se estrellara, antes de que la iniciativa Dharma llegara, antes de que se editara &#8216;<strong>De ratones y hombres<\/strong>&#8216;. Yo no creo que sea Jacob, puede ser un parte de \u00e9l, una escisi\u00f3n oscura, pero voto porque es su enemigo ancestral. En fin, <em>preguntas<\/em>, \u00bfQui\u00e9n es el humo negro? \u00bfPor qu\u00e9 est\u00e1 encerrado en la Isla? \u00bfQu\u00e9 es lo que tiene que hacer para liberarse? \u00bfPara qu\u00e9 necesita a Sawyer?<\/p>\n<p><strong>2.- El ni\u00f1o.<\/strong><\/p>\n<p align=\"center\"><img loading=\"lazy\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\" alt=\"\" width=\"500\" height=\"264\" \/><\/p>\n<p>Cuando Locke libera a Richard ve un ni\u00f1o rubio, vestido como los Otros al que parece que Richard no puede ver. El ni\u00f1o tiene las <strong>manos ensangrentadas<\/strong>, <em>pregunta<\/em>, \u00bfes una profec\u00eda de lo que est\u00e1 por llegar o acusa a Locke de asesino? Sawyer le ve m\u00e1s tarde, o eso parece, al no ser que sea un mentiroso. Adem\u00e1s, el ni\u00f1o se dirige a Locke y le dice: <strong>\u201cConoces las reglas, no puedes matarle\u201d<\/strong>. Mi primera teor\u00eda fue que era<strong> Jacob reencarnado<\/strong>, pero despu\u00e9s de pensarlo podr\u00eda ser una<strong> encarnaci\u00f3n de la propia Isla<\/strong> u otro ente supremio y sobrenatural que arbitra la disputa ente Locke y Jacob. Este ni\u00f1o es uno de los dos grandes misterios de este espisodio, el primero viene a continuaci\u00f3n.<\/p>\n<p>3<strong>.- La cueva de Jacob.<\/strong><\/p>\n<p align=\"center\"><img loading=\"lazy\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\" alt=\"\" width=\"500\" height=\"283\" \/><\/p>\n<p>Locke lleva a Sawyer a una cueva en la que est\u00e1n escritos en las paredes los nombres de los <strong>candidatos a sustitutos de Jacob<\/strong> para vigilar la Isla aunque Locke dice que a la Isla no hace falta protegerla de nada. Los nombres tachados son los de los muertos, los que todav\u00eda siguen vivos tienen sus nombres intactos. Al lado de cada nombre aparece un n\u00famero, que curiosamente, son los n\u00fameros que llevan pululando por la serie desde la temporada 1. Locke le dice a Sawyer que <strong>Jacob estaba obsesionado con los n\u00fameros<\/strong>. Todos se han cruzado con Jacob en alg\u00fan momento de su vida y le han prometido algo que despu\u00e9s no han cumplido.<\/p>\n<p>En la cueva tambi\u00e9n hay una balanza. En la balanza hay dos piedras, una blanca y otra negra Locke la tira y la desequilibra. <em>Pregunta<\/em> \u00bfTiene alg\u00fan significado la balanza?<\/p>\n<p><strong>L1<\/strong><\/p>\n<p align=\"center\"><img loading=\"lazy\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\" alt=\"\" width=\"500\" height=\"291\" \/><\/p>\n<p>En la<strong> l\u00ednea temporal alternativa<\/strong> vemos la vida de Locke. No se parece a la que ten\u00eda antes del accidente. En esta vive con una mujer llamada Helen y es medianamente feliz con ella aunque sigue en silla de ruedas. Adem\u00e1s, vemos como es despedido, como se encuentra con Hugo, que es<strong> due\u00f1o de una empresa de trabajo temporal<\/strong>, se ofrece a ayudarle y le env\u00eda con Rose. Tambi\u00e9n aparece Ben cuando Locke est\u00e1 haciendo de profesor sustituto, Linus es el profesor de Historia. En la l\u00ednea temporal contada anteriormente Locke viv\u00eda solo y amargado, su relaci\u00f3n con el sexo opuesto se limitaba a conversaciones con una mujer que trabajaba en una<strong> l\u00ednea er\u00f3tica<\/strong> y que tambi\u00e9n se llamaba Helen (seguramente fuera la misma).<\/p>\n<p>Esta segunda l\u00ednea temporal no hay mucho que contar, tan s\u00f3lo que Jacob de momento, no ha aparecido por ninguna parte y yo no tengo ni idea de como van a justificar tanto encuentro casual. Los <strong>pasajeros del 815 de Oceanic<\/strong> no se conoc\u00edan&#8230;<\/p>\n<p>&#8211; <a href=\"http:\/\/blogs.elnortedecastilla.es\/deathblog\/\" rel=\"nofollow\" target=\"_blank\">MEG<\/a> &#8211;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recuperamos el nivel de los primeros cap\u00edtulos despu\u00e9s del sos\u00edsimo 6&#215;03 y su protagonista Kate. En este episodio se desvelas nuevas cosas y se despiertan varias preguntas. Si en el anterior, no ve\u00edamos a Locke, en este no vemos a los del templo pero no importa. Locke (o quien quiera que sea) es el protagonista [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[135,156],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/21"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/21\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/media?parent=21"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/categories?post=21"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/tags?post=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}