{"id":29,"date":"2010-04-28T11:05:00","date_gmt":"2010-04-28T11:05:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/pasameelmando\/?p=29"},"modified":"2010-04-28T11:05:00","modified_gmt":"2010-04-28T11:05:00","slug":"los-tres-hurley","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/2010\/04\/28\/los-tres-hurley\/","title":{"rendered":"Los tres de Hurley"},"content":{"rendered":"<p>\u00bfQui\u00e9n dir\u00eda que el bonach\u00f3n Hurley de &#8216;<a id=\"link_0\" title=\"http:\/\/www.laguiatv.com\/serie\/ficha\/Perdidos\/144079\" href=\"http:\/\/www.laguiatv.com\/serie\/ficha\/Perdidos\/144079\" rel=\"nofollow external\" target=\"_blank\">Perdidos<\/a>&#8216; <strong>cumple hoy 37 a\u00f1os<\/strong>? Bueno, en realidad \u00e9l no, sino el actor que le da vida, Jorge Garc\u00eda. Pues s\u00ed, se\u00f1ores, 37 tacos tiene el na\u00fafrago m\u00e1s saludable de todos, y nosotros queremos celebrarlo recordando sus tres mejores momentos en la serie. Tarea complicada teniendo en cuenta que Hugo &#8216;Hurley&#8217; Reyes es uno de los &#8216;losties&#8217; originales -los supervivientes del accidente de avi\u00f3n- y que desde la primera temporada ha tenido un papel destacado en la trama. Pero hay que intentarlo, y ya que con \u00e9l comparto apellido -aunque yo lo llevo de nombre-, me he ofrecido.<\/p>\n<p>All\u00e1 van. Los tres mejores momentos de Hurley en &#8216;Perdidos&#8217;.<\/p>\n<p><img id=\"img_0\" class=\"imgcen\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\" alt=\"\" \/><\/p>\n<h3><span style=\"color: #00cccc;\"><!--more-->1. &#8220;Tienes un poco de Artz en el hombro&#8221; (1&#215;23)<\/span><\/h3>\n<p>El pobre Artz, un personaje de \u00e9sos de \u00faltima hora para hacer bulto, sale volando por los aires ante la mirada at\u00f3nita de Hurley, Jack, Locke, Kate y la francesa. Es lo que tiene la dinamita en mal estado, &#8216;dude&#8217;. Para quitar hierro al asunto -al fin y al cabo, \u00bfqui\u00e9n le va a echar de menos?-, Hurley lanza una de esas perlas que los fans de la serie a\u00fan recuerdan: &#8220;Tienes un poco de Artz en el hombro&#8221;. Tanta gracia hizo en su d\u00eda que recientemente la serie quiso rescatar el momento&#8230;<\/p>\n<h3><span style=\"color: #00cccc;\">2. La &#8216;Dharmaneta&#8217; (3X10)<\/span><\/h3>\n<p>Cansado de su mala suerte, Hurley decide tentarla y se lanza cuesta abajo con la furgoneta de la Iniciativa Dharma, abandonada desde hace unos 30 a\u00f1os. En esta arriesgada iniciativa le acompa\u00f1a Charlie, quien, aun sabiendo que est\u00e1 destinado a morir, se deja contagiar por el optimismo de su amigo. Un par\u00e9ntesis de alegr\u00eda y buen rollo entre tanto misterio.<\/p>\n<h3><span style=\"color: #00cccc;\">3. Cuatro temporadas resumidas en menos de un minuto (5&#215;02)<\/span><\/h3>\n<p>Al final del segundo cap\u00edtulo de la quinta temporada, Hurley, harto de mentir sobre los Oceanic 6, se atreve a contarle toda la verdad a su madre, y a su manera. Divertido discursillo. \u00a1<a id=\"link_0\" title=\"http:\/\/www.youtube.com\/watch?v=BMgNox3Zn6Y\" href=\"http:\/\/www.youtube.com\/watch?v=BMgNox3Zn6Y\" target=\"_blank\" rel=\"external nofollow\">No os lo perd\u00e1is<\/a>!<\/p>\n<p>Por <a id=\"link_0\" title=\"http:\/\/blogs.nortecastilla.es\/desdelabutaca\/posts\" href=\"http:\/\/blogs.elnortedecastilla.es\/desdelabutaca\/posts\" rel=\"nofollow\" target=\"_blank\">Reyloren<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n dir\u00eda que el bonach\u00f3n Hurley de &#8216;Perdidos&#8216; cumple hoy 37 a\u00f1os? Bueno, en realidad \u00e9l no, sino el actor que le da vida, Jorge Garc\u00eda. Pues s\u00ed, se\u00f1ores, 37 tacos tiene el na\u00fafrago m\u00e1s saludable de todos, y nosotros queremos celebrarlo recordando sus tres mejores momentos en la serie. Tarea complicada teniendo en cuenta [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,7],"tags":[63,112,113,135,156],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/29"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/29\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/media?parent=29"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/categories?post=29"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/tags?post=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}