{"id":35,"date":"2010-05-21T19:45:00","date_gmt":"2010-05-21T19:45:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/pasameelmando\/?p=35"},"modified":"2010-05-21T19:45:00","modified_gmt":"2010-05-21T19:45:00","slug":"como-crees-acabara-perdidos","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/2010\/05\/21\/como-crees-acabara-perdidos\/","title":{"rendered":"\u00bfC\u00f3mo crees que acabar\u00e1 &#039;Perdidos&#039;?"},"content":{"rendered":"<p><strong>\u00a13 d\u00edas! \u00a1\u00a13 d\u00edas!!<\/strong> Es el tiempo que queda para uno de los acontecimientos televisivos del a\u00f1o, un momento que muchos de nosotros deseamos que llegue ya y al mismo tiempo so\u00f1amos con que nunca ocurra, el final de &#8216;<A href=\"..\/pasameelmando\/tags\/perdidos\" title=\"http:\/\/blogs.nortecastilla.es\/pasameelmando\/tags\/perdidos\" id=\"link_0\">Perdidos<\/a>&#8216;. En P\u00e1same el Mando nos preguntamos c\u00f3mo puede ser ese final, qu\u00e9 gran misterio se revelar\u00e1 en el \u00faltimo segundo, y por eso os pedimos vuestra opini\u00f3n. <strong>\u00bfC\u00f3mo cre\u00e9is que acabar\u00e1 &#8216;Perdidos&#8217;?<\/strong><\/p>\n<p>\u00a1Y recordad! El <strong>lunes a las 6.30 de la ma\u00f1ana<\/strong>, <A href=\"..\/deathblog\/posts\" title=\"http:\/\/blogs.nortecastilla.es\/deathblog\/posts\" id=\"link_2\">MEG<\/a>  y <A href=\"..\/desdelabutaca\/posts\" title=\"http:\/\/blogs.nortecastilla.es\/desdelabutaca\/posts\" id=\"link_1\">Reyloren<\/a>  compartir\u00e1n con todos vosotros, <strong>en riguroso directo y desde nortecastilla.es<\/strong>, sus impresiones sobre la final. <A href=\"http:\/\/www.elnortedecastilla.es\/gente\/\" rel=\"nofollow\"         title=\"http:\/\/www.nortecastilla.es\/gente\/\" id=\"link_3\">\u00a1No os lo perd\u00e1is!<\/a> <\/p>\n<p><IMG src=\"\/pasameelmando\/files\/nocheperdida.jpg\" id=\"img_0\" class=\"imgcen\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a13 d\u00edas! \u00a1\u00a13 d\u00edas!! Es el tiempo que queda para uno de los acontecimientos televisivos del a\u00f1o, un momento que muchos de nosotros deseamos que llegue ya y al mismo tiempo so\u00f1amos con que nunca ocurra, el final de &#8216;Perdidos&#8216;. En P\u00e1same el Mando nos preguntamos c\u00f3mo puede ser ese final, qu\u00e9 gran misterio se [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/35"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}