{"id":39,"date":"2010-05-24T10:12:00","date_gmt":"2010-05-24T10:12:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/pasameelmando\/?p=39"},"modified":"2010-05-24T10:12:00","modified_gmt":"2010-05-24T10:12:00","slug":"el-final-perdidos-primeras-impresiones","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/2010\/05\/24\/el-final-perdidos-primeras-impresiones\/","title":{"rendered":"El final de Perdidos: primeras impresiones"},"content":{"rendered":"<p>Se acab\u00f3. &#8216;<a id=\"link_1\" title=\"http:\/\/blogs.nortecastilla.es\/pasameelmando\/tags\/perdidos\" href=\"..\/pasameelmando\/tags\/perdidos\">Perdidos<\/a>&#8216; se ha despedido para siempre de la televisi\u00f3n, y lo ha hecho con un <a id=\"link_0\" title=\"http:\/\/blogs.nortecastilla.es\/pasameelmando\/2010\/5\/24\/-te-gusto-final-perdidos-\" href=\"..\/pasameelmando\/2010\/5\/24\/-te-gusto-final-perdidos-\">final<\/a> <strong>pol\u00e9mico y memorable a la vez<\/strong>. Pol\u00e9mico porque, como ya intu\u00edamos, los \u00faltimos dos cap\u00edtulos <strong>no han dado respuesta a todas las inc\u00f3gnitas<\/strong> que la serie ha sembrado durante seis temporadas; y memorable, porque sus minutos finales han servido para rendir un <strong>homenaje a todos sus personajes<\/strong>, o por lo menos a los m\u00e1s importantes, y recordar los momentos m\u00e1s emotivos que hemos vivido con ellos.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" id=\"img_0\" class=\"imgcen aligncenter\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\" alt=\"\" width=\"500\" height=\"500\" \/><\/p>\n<p style=\"text-align: left;\">Por eso <strong>me ha gustado el final de &#8216;Lost&#8217;<\/strong>. Siempre he dicho que la raz\u00f3n principal del \u00e9xito de esta serie no eran sus misterios, que son muchos, sino su fuerza dram\u00e1tica, las historias tr\u00e1gicas de esos personajes solitarios que tanto nos han hecho re\u00edr y llorar, sobre todo llorar. Y eso es de lo que va este \u00faltimo cap\u00edtulo.<!--more--><\/p>\n<p>Hemos visto a incondicionales como Jack, Kate o Locke, a los siempre recordados Charlie, Juliet o Boone, y a otros menos habituales como Charlotte o Pierre Chang. Hemos presenciado <strong>reencuentros<\/strong> -fant\u00e1sticos Sawyer y Juliet, as\u00ed como Charlie y Claire-, <strong>despedidas<\/strong> -\u00a1Kate se decide!-, <strong>redenciones y gui\u00f1os al pasado<\/strong>. Hemos re\u00eddo con Hurley, llorado con Jack y sonre\u00eddo al ver a John Locke feliz de una vez por todas.<\/p>\n<p>Adem\u00e1s, hemos regresado atr\u00e1s en el tiempo, a aquel bosque de bamb\u00fa donde hace ya seis a\u00f1os un ojo se abr\u00eda de repente para dar comienzo a una serie que marcar\u00eda un antes y un desp\u00faes en la historia de la televisi\u00f3n, y tambi\u00e9n en la de Internet, un ojo que hoy, a las 8.15 hora espa\u00f1ola, se ha cerrado para siempre. <strong>\u00bfAlguien puede pensar en un final mejor para &#8216;Perdidos&#8217;?<\/strong><\/p>\n<h3>Explicaci\u00f3n poco convincente<\/h3>\n<p>Otra historia es c\u00f3mo se resuelven los misterios. Cierto es que muchos de ellos <strong>han quedado en el aire<\/strong>, a la espera de que los foros de los aficionados y sobre todo los extras de los DVD les den su explicaci\u00f3n -y c\u00f3mo lo disfrutaremos entonces-. Otros ya fueron solucionados hace tiempo, s\u00f3lo que de manera somera, pero suficiente para quienes queremos disfrutar de la serie sin entrar en debates de si los viajes en el tiempo son o no posibles.<\/p>\n<p>En cuanto a la famosa l\u00ednea alternativa, no puedo decir que me sienta satisfecha. Eso de que m\u00e1s que una realidad paralela es una especie de antesala del cielo, por llamarlo de alguna manera, no me convence. De hecho, parece que los guionistas <strong>se lo han sacado de la manga en el \u00faltimo minuto<\/strong>.<\/p>\n<p>Para colmo, el &#8220;Nos vamos a un concierto&#8221; de Desmond en el cap\u00edtulo anterior a \u00e9ste nos hab\u00eda dejado los dientes largos. Esper\u00e1bamos una batalla \u00e9pica, o un regreso en grupo a la isla que les hizo conocerse los unos a los otros y tambi\u00e9n a s\u00ed mismos.<\/p>\n<p>Pero no quiero a\u00f1adir m\u00e1s sobre esa explicaci\u00f3n. Trat\u00e1ndose de &#8216;Lost&#8217;, merece por lo menos un segundo visionado para buscar claves y asimilarlo todo.<\/p>\n<p>Prefiero quedarme con los reencuentros, el perd\u00f3n de Ben, el esperado &#8216;Te quiero de Kate&#8217; y el ojo de Jack, sobre todo el ojo de Jack.<\/p>\n<p><em>Por <\/em><a id=\"link_0\" title=\"http:\/\/blogs.nortecastilla.es\/desdelabutaca\/posts\" href=\"..\/desdelabutaca\/posts\">Reyloren<\/a><\/p>\n<p><a id=\"link_0\" title=\"http:\/\/blogs.nortecastilla.es\/pasameelmando\/2010\/5\/24\/-te-gusto-final-perdidos-\" href=\"..\/pasameelmando\/2010\/5\/24\/-te-gusto-final-perdidos-\">\u00bfTe gust\u00f3 el final de &#8216;Perdidos&#8217;?<\/a><\/p>\n<p><a id=\"link_1\" title=\"http:\/\/blogs.nortecastilla.es\/pasameelmando\/2010\/5\/24\/asi-hemos-seguido-directo-final-perdidos-\" href=\"..\/pasameelmando\/2010\/5\/24\/asi-hemos-seguido-directo-final-perdidos-\">As\u00ed comentamos el cap\u00edtulo mientras lo ve\u00edamos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se acab\u00f3. &#8216;Perdidos&#8216; se ha despedido para siempre de la televisi\u00f3n, y lo ha hecho con un final pol\u00e9mico y memorable a la vez. Pol\u00e9mico porque, como ya intu\u00edamos, los \u00faltimos dos cap\u00edtulos no han dado respuesta a todas las inc\u00f3gnitas que la serie ha sembrado durante seis temporadas; y memorable, porque sus minutos finales [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[92,156],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/39"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/39\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/media?parent=39"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/categories?post=39"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/tags?post=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}