{"id":599,"date":"2012-05-08T01:03:09","date_gmt":"2012-05-07T23:03:09","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/pasameelmando\/?p=599"},"modified":"2012-05-08T01:03:09","modified_gmt":"2012-05-07T23:03:09","slug":"juego-de-tronos-2x06-the-old-gods-and-the-new","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/2012\/05\/08\/juego-de-tronos-2x06-the-old-gods-and-the-new\/","title":{"rendered":"Juego de Tronos 2&#215;06. The Old Gods and the New"},"content":{"rendered":"<p>Salvajes. Salvajes a otro lado del Muro \u00bfo a este lado? No importa de que lado est\u00e9s mientras seas un ser humano. No pasa nada mientras puedas seguir respirando porque as\u00ed se puede traicionar, matar o masacrar a diestro y siniestro. <strong>&#8216;The Old Gods and the New&#8217;<\/strong> aunque parece que ya no quedan dioses en Poniente para nadie.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001.jpg\"><img class=\"aligncenter size-full wp-image-633\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/2012\/05\/08\/juego-de-tronos-2x06-the-old-gods-and-the-new\/\">Continuar leyendo<\/a> (spoilers)&#8230;<\/p>\n<p><!--more-->En Invernalia el maestre Luwin corre hacia la torre con los cuervos. Escribe una carta a toda prisa mientras se oyen gritos y golpes de batalla. Con el tiempo justo<strong> logra enviar un p\u00e1jaro.<\/strong> Mientras, Theon irrumpe en la habitaci\u00f3n de Bran para despertarle y decirle que<strong> ha tomado la fortaleza<\/strong>, que se rinda. Bran incr\u00e9dulo, no asimila la traici\u00f3n de su &#8216;hermano&#8217;. El Se\u00f1or de Invernalia no se lo piensa mucho y se rinde no sin antes preguntar si siempre los ha odiado. \u00c9l es un hijo del Hierro, Theon, digno s\u00fabdito de su padre traiciona a los que eran su familia.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001b.jpg\"><img class=\"aligncenter size-full wp-image-611\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001b.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001b.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001b-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Es m\u00e1s, <strong>el pr\u00edncipe del Hierro<\/strong> no duda en ejecutar a Ser Rodrick cuando le hace frente, cuando le llama traidor y le recuerda su infancia en Invernalia. Por lo menos <strong>es \u00e9l mismo quien lo mata<\/strong>, no de un tajo limpio sino de varios mientras se salpica de sangre y echa la bilis por los a\u00f1os acumulados como reh\u00e9n. No funcionan ni la petici\u00f3n de Luwin ni las s\u00faplicas de Bran, ni siquiera el llanto de Rickon. Como el propio Rodrik le recuerda:<\/p>\n<blockquote><p><span style=\"font-family: Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif;\">&#8220;Que los dioses te protejan Theon Greyjoy. Ahora est\u00e1s perdido de verdad&#8221;<\/span><\/p><\/blockquote>\n<p>Osha, la salvaje, hace lo puede. Le pide a Theon servir como lanza aunque al listillo, porque todos sabemos lo listo que es, se\u00a0r\u00ede\u00a0de ella y la desprecia. Es una criada y una salvaje.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-258_0001.jpg\"><img class=\"aligncenter size-full wp-image-652\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-258_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-258_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-258_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Por la noche vuelve a insistir pero esta vez con algo que nuestro joven semental al que le gustan m\u00e1s dos tetas que&#8230; cualquier otra otra cosa no puede rechazar. En la resaca postcoital <strong>Osha sale de la cama para sacar a Bran y a Rickon de Invernalia<\/strong> junto con Hodor y con los dos lobos. Ella es lo bastante salvaje para saber que <strong>Bran es algo especial<\/strong>, que sus sue\u00f1os no son normales aunque no se lo quiera confirmar. Para eso est\u00e1 dispuesta a arriesgar su vida y mucho m\u00e1s.<\/p>\n<h3>&#8211; El otro lado del Muro<\/h3>\n<p><strong>La expedici\u00f3n de Jon, Quoryn<\/strong> y sus otros acompa\u00f1antes sigue adelante. M\u00e1s adelantado todav\u00eda va Fantasma a pesar de que Jon le llama.<\/p>\n<blockquote><p><span style=\"font-family: Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif;\">&#8220;No se puede domar lo salvaje&#8221;<\/span><\/p><\/blockquote>\n<p>Y ah\u00ed est\u00e1 Quoryn dando consejos a Jon mientras marchan al campamento de los salvajes apra matar a Mance, o lo que haga falta. No se tienen muy claro para que. Ni siquiera el explorador que lleva a\u00f1os deambulando por las tierras heladas<strong> para defender Los Siete Reinos,<\/strong> para <strong>defender a los hombres<\/strong>&#8230; o eso se dicen por las noches. Nadie los echar\u00e1 de menos, la muerte de uno de ellos significa la protecci\u00f3n de todos esos nobles que comen, follan y se traicionan.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-052_0001.jpg\"><img class=\"aligncenter size-full wp-image-616\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-052_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-052_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-052_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Por fin llegan al campamento y atacan. Entonces es cuando Jon se da cuenta de que <strong>uno de los salvajes es una mujer<\/strong>. Le pregunta por su nombre. Ygritte. \u00a0Despu\u00e9s del interrogatorio tienen que matarla. Aunque Jon se ofrece y le dejan atr\u00e1s no es capaz de asesinarla. <strong>Su honor no se lo permite<\/strong>. Es el campe\u00f3n del honor junto con su padre, pero \u00e9l est\u00e1 muerto y \u00e9l es digno heredero.<\/p>\n<p>Antes las dudas Ygritte huye. As\u00ed podemos ver esos paisajes islandeses que te dejan la boca abierta. Despu\u00e9s no los vas a poder cerrar&#8230; del fr\u00edo. Cuando la alcanza la derriba pero sigue sin poder matarla a pesar de que sabe que es peligrosa, que revelar\u00e1 su posici\u00f3n, que contar\u00e1 cu\u00e1ntos son. Se queda sin tiempo porque la luz se va.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-235_0001.jpg\"><img class=\"aligncenter size-full wp-image-650\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-235_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-235_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-235_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p><strong>Siguen caminando en busca de los Hermanos Negros<\/strong>\u00a0pero no dan con ellos. Jon se muestra convencido de que los encontrar\u00e1n&#8230; Ygritte no tiene tanta fe. Cuando se tumba a dormir reclama a Jon con esa escusa m\u00e1s vieja de la tos de darse calor.<\/p>\n<p>Reconozco que los frotamientos de la muchacha, la incomodidad de Jon y su mosqueo tienen su gracia. Tambi\u00e9n la tiene la cara de satisfacci\u00f3n pillina de la salvaje.<\/p>\n<h3>&#8211; Harrenhal<\/h3>\n<p>Arya sigue como copera de Tywin, a su lado. El gran Lord la quiere cerca, sospecha, algo se huele. Tywin le echa la bronca a uno de sus abanderados para variar. Se ha equivocado al enviar una carta y se la ha mandado a un vasallo de Robb. Con su gracia habitual el Lannister le echa de la habitaci\u00f3n. Tan justo, san serio, san severo. Ese car\u00e1cter sin un \u00e1pice de sentido del humor que <strong>Tyrion tanto odia<\/strong>.<\/p>\n<p><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-067_0001.jpg\"><img class=\"aligncenter\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-067_0001.jpg\" alt=\"\" width=\"580\" \/><\/a><\/p>\n<p style=\"text-align: left;\">El le\u00f3n se da cuenta de que Arya sabe leer. Cada vez est\u00e1 m\u00e1s cerca. Cada vez sospecha m\u00e1s. Entonces llega Me\u00f1ique.<strong> Lord Baelish entra como emisario de los Tyrell<\/strong>. Se los ofrece a Tywin. Loras quiere venganza y Margaery ser reina a toda costa.<\/p>\n<p>Los dos hablan sin reparar en Arya que intenta, por todos los medios, pasar desapercibida para el anterior Consejero de la Moneda. Los nervios est\u00e1n a flor de piel y la copera<strong> tira el vino encima de Me\u00f1ique<\/strong> que entonces la ve. La reconoce. Y no dice nada a pesar de que en cuanto puede le echa otro vistazo para confirmar sus sospechas. Baelish no abre la boca y el fantasma no sale. Mejor para \u00e9l. <strong>El silencio es por Cathelyn, \u00bfo por un plan posterior?<\/strong>.<\/p>\n<p><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-084_0001b.jpg\"><img class=\"aligncenter\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-084_0001b.jpg\" alt=\"\" width=\"580\" \/><\/a><\/p>\n<p>Mientras recoge la mesa Arya encuentra una carta que habla sobre su hermano. Entretiene a Tywin, que, no se muy bien porqu\u00e9 tiene un atisbo de bondad cada vez que habla con ella, mientras roba el escrito. <strong>El se\u00f1or de Roca Casterly habla de su padre<\/strong>, de como era un buen hombre que casi destruye su casa y acaba con el apellido Lannister. En medio de sus recuerdos env\u00eda a Arya a por le\u00f1a momento que aprovecha para leer la carta detenidamente.<\/p>\n<p>Arya camina y <strong>choca con Armory Roach<\/strong> que le pregunta hasta que se da cuenta de que la ni\u00f1a oculta algo. Arya corre, como siempre, mientras busca a <strong>Jaqen H&#8217;ghar<\/strong>. Despu\u00e9s de varios equ\u00edvocos lo encuentra y pronuncia el nombre del caballero para que acabe con \u00e9l. R\u00e1pido. <strong>Cuando Roach entra en la sala con Tywin ya est\u00e1 muerto<\/strong>.<\/p>\n<h3>&#8211; Desembarco del Rey<\/h3>\n<p>Cersei se despacha a gusto con su hermano:<\/p>\n<p>&#8220;Rezo porque un d\u00eda ames a alguien. Rezo para que la quieras tanto que cuando cierres los ojos veas su cara. Rezo para que te pase eso. Quiero que sepas lo que es amar a alguien, lo que es amar a alguien con el coraz\u00f3n para que te lo pueda arrebatar&#8221;.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-125_0001.jpg\"><img class=\"aligncenter size-full wp-image-635\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-125_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-125_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-125_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p><strong>Sansa, Joffrey y \u00a0Tommen<\/strong> tambi\u00e9n est\u00e1n en la <strong>despedida deMyrcella<\/strong> que ha embarcado hacia Dorne. Mientras la princesa llora y el Gran Sept\u00f3n reza su hermano peque\u00f1o la acompa\u00f1a en el llanto mientras que el mayor se r\u00ede de su debilidad. Sansa intenta defenderle pero cuando ve la ira del Rey fija en ella recula. Su hermano no es un pr\u00edncipe as\u00ed que no importa.<\/p>\n<p>Se retiran del muelle y comienzan a caminar.<strong> El s\u00e9quito recorre las calles<\/strong> cuando un hombre grita hurras al Rey. Entonces, dos o tres voces comienzan a insultarlo y \u00a0alguien le tira algo a la cara que alcanza de lleno a Joffrey. El ni\u00f1o, ya sabemos, paciencia tiene poca as\u00ed que insta a los guardias a que arremetan contra la multitud. En el caos -cap\u00edtulo Sept\u00f3n a lo The Walking Dead aparte- <strong>Sansa se pierde<\/strong>. Corre como todos hasta que unos hombres le acorralan.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001b.jpg\"><img class=\"aligncenter size-full wp-image-639\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001b.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001b.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001b-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Tyrion grita a Joffrey. No le importa Sansa y la Mano solo <strong>la quiere como moneda de cambio para Jaime<\/strong>. El Perro sale corriendo a buscarla. Destripa a uno de los casi-violadores y mata a los otros dos. <strong>El Rey mezquino y el Perro honorable<\/strong>. Devuelve a Sansa y recuerda a Tyrion:<\/p>\n<blockquote><p><span style=\"font-family: Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif;\">&#8220;No lo he hecho por ti&#8221;<\/span><\/p><\/blockquote>\n<p>Poco a poco esa relaci\u00f3n rara. Esa fascinaci\u00f3n especial entre Sansa y el Perro se sigue oliendo en un empe\u00f1o por salvarla de todo mal mientras sea posible.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001.jpg\"><img class=\"aligncenter size-full wp-image-655\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Shae limpia las heridas a Sansa. No tienden porqu\u00e9 la odian y la doncella le da la respuesta. Ella es y tiene todo lo que ellos nunca tendr\u00e1n:<\/p>\n<blockquote><p><span style=\"font-family: Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif;\">&#8220;Odio m\u00e1s al Rey que a cualquiera de ellos&#8221;<\/span><\/p><\/blockquote>\n<p>Shae le manda callar, le dice que cualquiera podr\u00eda oir la conversaci\u00f3n que <strong>no se f\u00ede de nadie<\/strong>. Pero Sansa se f\u00eda de Shae y se lo dice pero ella le insiste y piensa no se sabe muy bien si en alguien del pasado o en <strong>Tyrion que la ha enviado como criada<\/strong> en vez de mantenerla en su cama.<\/p>\n<h3>&#8211; Campamento de Robb<\/h3>\n<p><strong>El Rey del Norte<\/strong> saluda a todos en su campamento hasta que se encuentra con la corta piernas, Lady Talisa. Ella no est\u00e1 muy contenta con el t\u00edtulo y despu\u00e9s de coqueteo por ah\u00ed coqueteo por all\u00e1 acaba reconociendo que es noble. En esas que <strong>llega Cathelyn<\/strong> a cortarles el rollo aunque sea solo por la mirada que le echa a su hijo merece la pena. Pero una madre es una madre y ya se encarga ella de<strong> recordarle su compromiso con los Frey<\/strong>. No puede seguir a su coraz\u00f3n por m\u00e1s que ella quiera que lo haga. Entonces llega Lord Bolton con una carta de Invernalia. El cuervo de Luwin ha llegado a su destino.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-222_0001.jpg\"><img class=\"aligncenter size-full wp-image-648\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-222_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-222_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-222_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Cathelyn, Robb y Bolton discuten sobre Invernalia. <strong>Robb quiere ir a tomarla<\/strong>, Cathelyn se pone en plan &#8220;ya te lo dije&#8221; pero el Lord lo tiene claro, una carta a su bastardo y retomar\u00e1 la fortaleza para el Rey del Norte &#8220;en menos de una luna&#8221;. <strong>Robb pide que le devuelvan a sus hermanos<\/strong>, ellos son su prioridad, pero tambi\u00e9n<strong> quiere a Theon vivo<\/strong> para poder preguntarle porqu\u00e9 y despu\u00e9s matarle como digno hijo de su padre.<\/p>\n<h3>&#8211; Qarth<\/h3>\n<p>En el Este <strong>a Daenerys las cosas no le van bien<\/strong>. Va a pedir barcos a los distintos mercaderes pero se r\u00eden de ella, <strong>no creen en su capacidad de batalla<\/strong>, ni en su capacidad para reinar, le niegan los barcos directamente o <strong>le piden a cambio sexo<\/strong>. \u00a0Xaro aprovecha para recordar que si sse hubiera casado con \u00e9l ahora tendr\u00eda barcos y no tendr\u00eda que recorrer a todos los t\u00edos con pasta de la ciudad para buscar favores prometiendo cosas que todav\u00eda no tiene.<\/p>\n<p style=\"text-align: center;\"><a href=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001.jpg\"><img class=\"aligncenter size-full wp-image-661\" title=\"j\" src=\"\/pasameelmando\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001.jpg\" alt=\"\" width=\"580\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001.jpg 720w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001-300x167.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>Pero <strong>lo peor para Daenerys de la Tormenta, de la Sangre del Drag\u00f3n y bla bla bla todav\u00eda est\u00e1 por llegar<\/strong> y es que al llegar a la residencia de Xaro sus soldados, sus Jinetes de Sangre, incluso su esclava est\u00e1 muerta y <strong>los dragones no est\u00e1n<\/strong>. Un hombre cubierto de metros y metros de tela y con la cara oculta carga una cesta con ellos dentro mientas se encamina hacia una torre.<\/p>\n<p>Promo. 2&#215;06 &#8216;The Old Gods and the New&#8217;<\/p>\n<p>http:\/\/www.youtube.com\/watch?v=qFufrDVNGhg<\/p>\n<p>Galer\u00eda de fotos<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-599 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001e.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001e-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001d.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001d-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001c.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-272_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-272_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-271_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-271_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-264_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-264_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001c.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-262_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-259_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-259_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-259_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-259_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-258_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-258_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-254_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-254_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-235_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-235_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-223_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-223_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-222_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-222_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-213_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-213_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-203_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-203_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-193_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-193_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-172_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-172_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-160_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-160_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-146_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-146_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-146_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-146_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-134_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-134_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-132_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-128_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-128_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-126_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-126_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-125_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-125_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-123_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-115_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-115_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-108_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-108_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-107_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-107_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-102_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-102_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-087_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-087_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-087_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-087_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-086_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-086_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-086_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-086_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-084_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-084_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-084_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-084_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-072_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-072_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-071_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-071_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-067_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-067_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-066_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-066_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-062_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-062_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-058_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-058_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-052_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-052_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001f.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001f-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001e.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001e-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001d.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001d-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001c.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-050_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-042_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-042_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-042_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-042_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-033_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-033_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-033_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-033_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001e.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001e-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001d.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001d-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001c.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001c-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001b.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001b-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-022_0001-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001f.jpg\"><img width=\"150\" height=\"150\" src=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/10\/2012\/05\/jdt.2x06.VOSE-273_0001f-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p><a class=\"twitter-follow-button\" href=\"https:\/\/twitter.com\/australia105\" data-show-count=\"false\" data-lang=\"es\" rel=\"external nofollow\">Seguir a @australia105<\/a><br \/>\n<script type=\"text\/javascript\">\/\/ <![CDATA[\n!function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(!d.getElementById(id)){js=d.createElement(s);js.id=id;js.src=\"\/\/platform.twitter.com\/widgets.js\";fjs.parentNode.insertBefore(js,fjs);}}(document,\"script\",\"twitter-wjs\");\n\/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salvajes. Salvajes a otro lado del Muro \u00bfo a este lado? No importa de que lado est\u00e9s mientras seas un ser humano. No pasa nada mientras puedas seguir respirando porque as\u00ed se puede traicionar, matar o masacrar a diestro y siniestro. &#8216;The Old Gods and the New&#8217; aunque parece que ya no quedan dioses en [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[13,121,176,199],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/599"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/pasameelmando\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}