{"id":100,"date":"2009-05-23T16:27:00","date_gmt":"2009-05-23T16:27:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/rafavega\/?p=100"},"modified":"2009-05-23T16:27:00","modified_gmt":"2009-05-23T16:27:00","slug":"defensa-capo","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/defensa-capo\/","title":{"rendered":"Defensa de capo"},"content":{"rendered":"<p><em>(El Norte de Castilla, 23 de mayo de 2009)<\/p>\n<p><\/em><\/p>\n<div class=\"p\">Al Capone acab\u00f3 entre rejas por evadir impuestos. En Chicago se conformaron con eso para librarse de su particular estilo empresarial. Desde entonces los abogados se ponen en guardia cuando sus clientes soportan una investigaci\u00f3n de Hacienda. Si Capone, un tipo listo que supo limpiarse las manchas de sangre, fue incapaz de ocultar el cad\u00e1ver contable, no hay que desde\u00f1ar esa porci\u00f3n de la defensa para contener los asaltos judiciales. A G\u00f3mez de Lia\u00f1o, letrado de Jos\u00e9 Manuel M\u00e9ndez, le ha reconfortado se\u00f1alar que su defendido no ha sido acusado de delito fiscal tras la investigaci\u00f3n de sus ingresos. Y no porque no haya sido descubierta una insolente tendencia a la mendacidad, sino porque el l\u00edmite monetario del delito es superior al de la injustificaci\u00f3n evidente de dinero y patrimonio. <\/div>\n<div class=\"p\">M\u00e9ndez no es Al Capone. Nadie busca manchas de sangre en su ropa ni alambiques en su garaje. Pero su defensa esgrime alivios que s\u00f3lo un g\u00e1ngster sin escr\u00fapulos escuchar\u00eda complacido. Siempre decepciona ver a un cargo p\u00fablico esconderse tras los recovecos legales. Su serpenteo para librarse de una acusaci\u00f3n por fraude fiscal extiende, entre vecinos y votantes de Arroyo, la sensaci\u00f3n de que han sido defraudados a niveles que dejan el pecuniario por los suelos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>(El Norte de Castilla, 23 de mayo de 2009) Al Capone acab\u00f3 entre rejas por evadir impuestos. En Chicago se conformaron con eso para librarse de su particular estilo empresarial. Desde entonces los abogados se ponen en guardia cuando sus clientes soportan una investigaci\u00f3n de Hacienda. Si Capone, un tipo listo que supo limpiarse las [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-100","post","type-post","status-publish","format-standard","hentry","category-del-dia"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/posts\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/posts\/100\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/media?parent=100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/categories?post=100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/tags?post=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}