{"id":104,"date":"2009-10-03T19:15:00","date_gmt":"2009-10-03T19:15:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/rafavega\/?p=104"},"modified":"2009-10-03T19:15:00","modified_gmt":"2009-10-03T19:15:00","slug":"veinte-mil-ripios","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/veinte-mil-ripios\/","title":{"rendered":"Veinte mil ripios"},"content":{"rendered":"<div class=\"p\"><em>(El Norte de Castilla, 3 de octubre de 2009)<\/em><br \/>\n<big>Uno de mis m\u00e1s queridos maestros ha llegado a advertirme, no hace mucho, de que mi inclinaci\u00f3n por valorar la cantidad en los aspectos vitales hace buenas migas con el materialismo dial\u00e9ctico. Yo cre\u00eda que casaba mejor con mi apego por cierto naturalismo aunque la raz\u00f3n, seguramente, est\u00e1 de su parte.<br \/>\nSin embargo, esta querencia no es s\u00f3lo fruto de mi falta de fe en lo excluyente, como lo ultra terreno (que tambi\u00e9n), sino convicci\u00f3n de que sin cantidad no hay margen para nada m\u00e1s, calidad incluida; de que sin d\u00edas no los habr\u00e1 felices; de que sin obras no las habr\u00e1 maestras, de que sin ensayos no habr\u00e1 modo de acertar, al menos, una vez en la vida. La cantidad es el arma secreta de la naturaleza para conseguir lo que se proponga, ya sea poner un oc\u00e9ano entre \u00c1frica y Am\u00e9rica o conseguir que una versi\u00f3n evolucionada de l\u00e9mur, acabe pisando la Luna.<br \/>\nPor eso siempre aspir\u00e9, al margen de mis gustos y los gustos de los dem\u00e1s, a la longevidad y a la cuant\u00eda ingente. As\u00ed que lo primero que me vino a la cabeza, tras conocer el fallecimiento de &#8216;Ans\u00farez&#8217;, fue el c\u00e1lculo aproximado de todos los ripios que atesora la Hemeroteca de EL NORTE desde que Francisco de Coss\u00edo dispuso y, sin duda, tan vasto arsenal s\u00f3lo puede despertar una profunda admiraci\u00f3n<\/big>. <\/div>\n","protected":false},"excerpt":{"rendered":"<p>(El Norte de Castilla, 3 de octubre de 2009) Uno de mis m\u00e1s queridos maestros ha llegado a advertirme, no hace mucho, de que mi inclinaci\u00f3n por valorar la cantidad en los aspectos vitales hace buenas migas con el materialismo dial\u00e9ctico. Yo cre\u00eda que casaba mejor con mi apego por cierto naturalismo aunque la raz\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-104","post","type-post","status-publish","format-standard","hentry","category-del-dia"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/posts\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/posts\/104\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/media?parent=104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/categories?post=104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/rafavega\/wp-json\/wp\/v2\/tags?post=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}