{"id":184,"date":"2010-03-03T08:07:00","date_gmt":"2010-03-03T08:07:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/?p=184"},"modified":"2010-03-03T08:07:00","modified_gmt":"2010-03-03T08:07:00","slug":"transparencia-opaca","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/2010\/03\/03\/transparencia-opaca\/","title":{"rendered":"Transparencia opaca"},"content":{"rendered":"<p><BIG>El presidente del Congreso dice que los ciudadanos van a dejar a un lado los prejuicios sobre los diputados. \u00a1Criatura\u2026! Resulta que las dos c\u00e1maras del poder legislativo han colgado en la Red las actividades privadas de quienes apenas calientan su esca\u00f1o en Madrid. Nuestras queridas se\u00f1or\u00edas han emborronado unos formularios en los que esbozan apuntes de su otro yo. Jos\u00e9 Bono no tiene precio como vendedor; otra cosa es rendirse ante su elocuencia, disfrazada de cantos de sirena. Ya conoc\u00edamos de largo las actividades de senadores y diputados, entre las que se encuentra levantar la mano aunque perjudiquen a los electores de la circunscripci\u00f3n que les elev\u00f3 al cargo, casi sin querer. Napole\u00f3n de La Mancha pretende convencernos de que esas cabezas sirven a Espa\u00f1a. Tomarse en serio a Bono es vivir en Jauja. Muchos de estos notables hacen caja. Despachos, consejos de administraci\u00f3n, tertulias y un largo etc\u00e9tera de influencia. El diputado del PP Gustavo de Ar\u00edstegui forma parte de un conglomerado empresarial por el que cobra. Aterriz\u00f3 como paracaidista en Zamora, pero la ha pisado unas horas y ni los suyos le tragan. No tiene tiempo: entre recrearse ante el espejo y escucharse hasta el paroxismo, imposible. Como viajero global, tanto traj\u00edn le report\u00f3 clarividencia. Obama triunf\u00f3 y don Gustavo se apresur\u00f3 a contar que \u00e9l ya se lo hab\u00eda anunciado a su esposa a\u00f1os atr\u00e1s. Su cabeza no est\u00e1 en Zamora sino en convertirse en ministro de Exteriores con Rajoy. \u00a1Ay\u2026!<\/p>\n<p>En la misma provincia, la senadora socialista Ana S\u00e1nchez compatibiliza su asiento con el del Ayuntamiento de la capital. Otra turbulencia que a\u00f1adir al canasto: s\u00f3lo acepta dietas y otras menudencias, aparte de emponzo\u00f1ar a su partido. Concejala o senadora; morder dos cargos puede hacer creer que se est\u00e1 traicionando al electorado, y S\u00e1nchez no goza del don de la ubicuidad.<\/p>\n<p>Tras la gloria de los grandes \u00e9xitos transparentes, se baraja la idea de hacer p\u00fablico el patrimonio de todas las se\u00f1or\u00edas. Se trata de poner a prueba la paciencia de los ciudadanos: \u00bfvan a contarnos lo que amasaron por culpa de nuestra inconsciencia? Seamos serios y dejemos de tomarle el pelo a la gente. Tantos cristales superpuestos impiden ver el Sol.<\/BIG><\/p>\n<p><EM>Publicado en El Norte de Castilla el 3 de marzo de 2010<\/EM><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del Congreso dice que los ciudadanos van a dejar a un lado los prejuicios sobre los diputados. \u00a1Criatura\u2026! Resulta que las dos c\u00e1maras del poder legislativo han colgado en la Red las actividades privadas de quienes apenas calientan su esca\u00f1o en Madrid. Nuestras queridas se\u00f1or\u00edas han emborronado unos formularios en los que esbozan [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5,8],"tags":[68,94,166,274,346,535,646,758,854,880,1004,1065,1090,1264],"class_list":["post-184","post","type-post","status-publish","format-standard","hentry","category-articulos-en-el-norte-de-castilla","category-comunicacion","category-especies-politicas","tag-ana","tag-aristegui","tag-bono","tag-congreso","tag-diputados","tag-gustavo","tag-jose","tag-mancha","tag-napoleon","tag-obama","tag-rajoy","tag-sanchez","tag-senadores","tag-zamora"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/posts\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/comments?post=184"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/posts\/184\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/categories?post=184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/robertocarbajal\/wp-json\/wp\/v2\/tags?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}