{"id":35,"date":"2009-09-30T11:52:00","date_gmt":"2009-09-30T11:52:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/tuopinas\/?p=35"},"modified":"2009-09-30T11:52:00","modified_gmt":"2009-09-30T11:52:00","slug":"feliz-antonio-gonza","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/2009\/09\/30\/feliz-antonio-gonza\/","title":{"rendered":"Desp\u00eddete de F\u00e9lix Antonio Gonz\u00e1lez"},"content":{"rendered":"<p>F\u00e9lix Antonio Gonz\u00e1lez, ex director de <A id=link_0 title=http:\/\/www.nortecastilla.es\/ href=\"http:\/\/www.elnortedecastilla.es\/\">El Norte de Castilla<\/A> El Norte de Castilla (1965-1967), poeta, pintor y riosecano, <A id=link_1 title=http:\/\/www.nortecastilla.es\/20090929\/local\/valladolid\/fallece-felix-antonio-gonzalez-200909291423.html href=\"http:\/\/www.elnortedecastilla.es\/20090929\/local\/valladolid\/fallece-felix-antonio-gonzalez-200909291423.html\">falleci\u00f3 ayer en Valladolid<\/A> a los 88 a\u00f1os de edad. En este espacio puedes dejar tu mensaje de apoyo a la familia, compartir con los dem\u00e1s el recuerdo que guardas del periodista o simplemente dedicarle unas l\u00edneas.<\/p>\n<p><IMG class=imgcen id=img_0 title=http:\/\/elcastellano.nortecastilla.es\/autores\/gonz%C3%A1lez-f%C3%A9lix-antonio src=\"\/tuopinas\/wp-content\/uploads\/sites\/9\" href=\"http:\/\/elcastellano.nortecastilla.es\/autores\/gonz%C3%A1lez-f%C3%A9lix-antonio\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00e9lix Antonio Gonz\u00e1lez, ex director de El Norte de Castilla El Norte de Castilla (1965-1967), poeta, pintor y riosecano, falleci\u00f3 ayer en Valladolid a los 88 a\u00f1os de edad. En este espacio puedes dejar tu mensaje de apoyo a la familia, compartir con los dem\u00e1s el recuerdo que guardas del periodista o simplemente dedicarle unas [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-35","post","type-post","status-publish","format-standard","hentry","category-felix-antonio-gonzalez"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}