{"id":88,"date":"2010-05-20T10:50:00","date_gmt":"2010-05-20T10:50:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/tuopinas\/?p=88"},"modified":"2010-05-20T10:50:00","modified_gmt":"2010-05-20T10:50:00","slug":"quien-debe-seguir-el-real-valladolid","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/2010\/05\/20\/quien-debe-seguir-el-real-valladolid\/","title":{"rendered":"\u00bfQui\u00e9n debe seguir en el Real Valladolid?"},"content":{"rendered":"<p>El <A href=\"http:\/\/www.canalpucela.es\/\" title=\"http:\/\/www.canalpucela.es\/\" id=\"link_0\">Real Valladolid<\/a>  jugar\u00e1 la pr\u00f3xima temporada en Segunda Divis\u00f3n con la vista puesta en un objetivo claro: <strong>regresar a Primera<\/strong>. En nortecastilla.es queremos saber <strong>qu\u00e9 jugadores<\/strong> consider\u00e1is vosotros que <strong>deber\u00edan permanecer en plantilla<\/strong> para que el club logre esa meta, o qui\u00e9nes, de los que ya se han ido, os gustar\u00eda que regresaran. <\/p>\n<p>\u00a1Opina!<\/p>\n<p><IMG src=\"\/tuopinas\/wp-content\/uploads\/sites\/9\" id=\"img_0\" class=\"imgcen\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Real Valladolid jugar\u00e1 la pr\u00f3xima temporada en Segunda Divis\u00f3n con la vista puesta en un objetivo claro: regresar a Primera. En nortecastilla.es queremos saber qu\u00e9 jugadores consider\u00e1is vosotros que deber\u00edan permanecer en plantilla para que el club logre esa meta, o qui\u00e9nes, de los que ya se han ido, os gustar\u00eda que regresaran. \u00a1Opina!<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-88","post","type-post","status-publish","format-standard","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/comments?post=88"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts\/88\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/media?parent=88"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/categories?post=88"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/tags?post=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}