{"id":97,"date":"2010-06-07T13:52:00","date_gmt":"2010-06-07T13:52:00","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/tuopinas\/?p=97"},"modified":"2010-06-07T13:52:00","modified_gmt":"2010-06-07T13:52:00","slug":"que-opinas-las-comunicaciones-valladolid","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/2010\/06\/07\/que-opinas-las-comunicaciones-valladolid\/","title":{"rendered":"\u00bfQu\u00e9 opinas de las comunicaciones de Valladolid?"},"content":{"rendered":"<p><IMG src=\"\/tuopinas\/wp-content\/uploads\/sites\/9\" id=\"img_0\" class=\"imgcen\">Una nueva mesa de Valladolid Avanza analiza la red de comunicaciones de Valladolid. D\u00e9janos tu opini\u00f3n y d\u00ednos si crees que la red es suficientemente buena. \u00bfHay buenas conexiones entre las principales autov\u00edas externas? \u00bfCrees que existe buena comunicaci\u00f3n con otras ciudades en tren, autocar y avi\u00f3n? \u00bfTe gusta c\u00f3mo se estructura el transporte p\u00fablico? \u00bfQu\u00e9 eliminar\u00edas y qu\u00e9 mejorar\u00edas?<\/p>\n<p> <strong>Deja ya<\/strong><strong> tus opiniones<\/strong> en los comentarios y en el especial de <A href=\"http:\/\/valladolidavanza.elnortedecastilla.es\" title=\"http:\/\/valladolidavanza.nortecastilla.es\" id=\"link_0\">Valladolid Avanza<\/a>  para que se las traslademos a los expertos que formar\u00e1n parte de la mesa de Valladolid Avanza. <strong>T\u00fa opinas y tu opini\u00f3n es importante, cu\u00e9ntanosla.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva mesa de Valladolid Avanza analiza la red de comunicaciones de Valladolid. D\u00e9janos tu opini\u00f3n y d\u00ednos si crees que la red es suficientemente buena. \u00bfHay buenas conexiones entre las principales autov\u00edas externas? \u00bfCrees que existe buena comunicaci\u00f3n con otras ciudades en tren, autocar y avi\u00f3n? \u00bfTe gusta c\u00f3mo se estructura el transporte p\u00fablico? [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-97","post","type-post","status-publish","format-standard","hentry","category-valladolid-2016"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/tuopinas\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}