{"id":1624,"date":"2013-08-09T00:25:50","date_gmt":"2013-08-08T23:25:50","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/?p=1624"},"modified":"2013-08-09T00:25:50","modified_gmt":"2013-08-08T23:25:50","slug":"un-soplo-del-mas-alla","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/2013\/08\/09\/un-soplo-del-mas-alla\/","title":{"rendered":"UN SOPLO DEL M\u00c1S ALL\u00c1"},"content":{"rendered":"<p><a href=\"\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2013\/08\/un-soplo-del-mas-alla.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1625\" title=\"un soplo del mas alla\" src=\"\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2013\/08\/un-soplo-del-mas-alla.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/3\/2013\/08\/un-soplo-del-mas-alla.jpg 620w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/3\/2013\/08\/un-soplo-del-mas-alla-225x300.jpg 225w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>Pierre Lacombe, pintor-falsificador, acude a un entierro y descubre que \u00e9l es el \u00fanico &#8220;invitado&#8221;. Al poco rato, alguien sale del ata\u00fad y le ataca. En los \u00faltimos d\u00edas, Lacombe hab\u00eda estado trabajando en un libro sobre una muy peculiar famila (la familia Fantome), varios de cuyos miembros hab\u00edan sido acusados de vampirismo, muy especialmente el \u00faltimo miembro de dicha familia, Nathalie Fantome, que acab\u00f3 sus d\u00edas apaleada y enterrada en una fosa com\u00fan.<\/p>\n<p>Paralelamente, Monique Lefevre acude a una \u00f3pera y al llegar al teatro s\u00f3lo la reciben una angustiosa soledad y una mujer muerta\u2026.<\/p>\n<p>Ambos cad\u00e1veres, los de Pierre Lacombe y Monique Lefevre, asomar\u00e1n de forma m\u00e1s o menos teatral a lo largo de la novela. Y no ser\u00e1n los \u00fanicos. Algunos de ellos aparecer\u00e1n sin una gota de sangre y con una sospechosa marca de dientes en el cuello\u2026<\/p>\n<p>Un novelista fracasado, Marc Cristel, que busca argumentos para un libro, comenzar\u00e1 a investigar hasta encontrar un cuadro de Nathalie Fantome y llegar al convencimiento de que ella es la persona que est\u00e1 matando a gente en Par\u00eds&#8230;.<\/p>\n<p>Historias de vampirismo, una mujer muerta que sale de un ata\u00fad, ambientes l\u00f3bregos y terror\u00edficos, misterios imposibles, cofres y ata\u00fades llenos de personas asesinadas a las que les han robado hasta el \u00faltimo litro de sangre. Mucho terror, mucha tensi\u00f3n y, de vez en cuando, como es habitual en Silver Kane, algunas pinceladas de humor. En este caso muy negro. La moda de los vampiros estaba en el ADN de Silver Kane hace ya muchos a\u00f1os. Con el viajamos para conocer a una nueva \u201creina de las sombras\u201d a una soberana del M\u00e1s All\u00e1 y del reino de la muerte. \u00a1Feliz (y terror\u00edfico) viaje!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pierre Lacombe, pintor-falsificador, acude a un entierro y descubre que \u00e9l es el \u00fanico &#8220;invitado&#8221;. Al poco rato, alguien sale del ata\u00fad y le ataca. En los \u00faltimos d\u00edas, Lacombe hab\u00eda estado trabajando en un libro sobre una muy peculiar famila (la familia Fantome), varios de cuyos miembros hab\u00edan sido acusados de vampirismo, muy especialmente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[126],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/1624"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/comments?post=1624"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/1624\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/media?parent=1624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/categories?post=1624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/tags?post=1624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}