{"id":1639,"date":"2013-08-29T08:23:31","date_gmt":"2013-08-29T07:23:31","guid":{"rendered":"http:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/?p=1639"},"modified":"2013-08-29T08:23:31","modified_gmt":"2013-08-29T07:23:31","slug":"preguntad-en-el-infierno","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/2013\/08\/29\/preguntad-en-el-infierno\/","title":{"rendered":"PREGUNTAD EN EL INFIERNO"},"content":{"rendered":"<p><a href=\"\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2013\/08\/preguntad-en-el-infierno-001.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-1640\" title=\"preguntad en el infierno 001\" src=\"\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2013\/08\/preguntad-en-el-infierno-001.jpg\" alt=\"\" width=\"207\" height=\"300\" srcset=\"https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/3\/2013\/08\/preguntad-en-el-infierno-001.jpg 1200w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/3\/2013\/08\/preguntad-en-el-infierno-001-207x300.jpg 207w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/3\/2013\/08\/preguntad-en-el-infierno-001-768x1112.jpg 768w, https:\/\/static-blogs.elnortedecastilla.es\/wp-content\/uploads\/sites\/3\/2013\/08\/preguntad-en-el-infierno-001-707x1024.jpg 707w\" sizes=\"(max-width: 207px) 100vw, 207px\" \/><\/a>Chris Laurens llega a un viejo caser\u00f3n abandonado perdido en un fantasmag\u00f3rico pueblo al que se accede tras cruzar un indicador de piedra en forma de l\u00e1pida en mitad de la carretera. All\u00ed se encuentra con su padre al que cre\u00eda muerto. Tiene un orificio de bala en la cabeza&#8230;. Cuando se despierta, porque todo ha sido un sue\u00f1o, su madre le dice que van a mudarse a otra ciudad. Al llegar a ella, Chris comprueba que es la misma de su sue\u00f1o, con el mismo e id\u00e9ntico caser\u00f3n. Su madre le dice que jam\u00e1s ha estado all\u00ed con anterioridad y que su padre muri\u00f3 de forma natural. Es el principio de una aut\u00e9ntica pesadilla para la joven\u2026.<\/p>\n<p>A partir de ese momento, Silver Kane se desmelenar\u00e1 presentando personajes y situaciones terror\u00edficas a toda pastilla. Un periodista que muere de forma extra\u00f1a en los alrededores de la t\u00e9trica mansi\u00f3n, un detective que se encarga del caso que aparentemente parece conocer una casa en la que nunca ha estado y que, tras enamorarse de Chris, consigue una orden judicial para abrir el ata\u00fad del padre de Chris. Al hacerlo comprueba aterrorizado que el ata\u00fad est\u00e1 vac\u00edo.<\/p>\n<p>Mientras tanto, el &#8220;difunto&#8221; comienza a aparecer por varios lugares&#8230;. Las investigaciones del detective se centran, a partir de este momento, en el trabajo que estaba realizando antes de su muerte o de su asesinato (si es que en realidad est\u00e1 muerto o fue asesinado). El &#8220;difunto&#8221; Ted Laurens era un cient\u00edfico que trabajaba en varios proyectos relacionados con el magnetismo (&#8220;El mundo entero es magnetismo. El universo se mantiene como est\u00e1 gracias al magnetismo. Las leyes que regulan los movimientos de los astros, y que descubri\u00f3 Newton, son magnetismo puro&#8221;)&#8230;.<\/p>\n<p>Al detective s\u00f3lo le queda preguntar en el infierno para saber qu\u00e9 ocurri\u00f3 con Ted Laurens. Y quiz\u00e1s lo haga. Con Silver Kane todo es posible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chris Laurens llega a un viejo caser\u00f3n abandonado perdido en un fantasmag\u00f3rico pueblo al que se accede tras cruzar un indicador de piedra en forma de l\u00e1pida en mitad de la carretera. All\u00ed se encuentra con su padre al que cre\u00eda muerto. Tiene un orificio de bala en la cabeza&#8230;. Cuando se despierta, porque todo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[126],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/1639"}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/comments?post=1639"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/1639\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/media?parent=1639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/categories?post=1639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/tags?post=1639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}