{"id":2860,"date":"2019-02-08T09:32:45","date_gmt":"2019-02-08T08:32:45","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/?p=2860"},"modified":"2019-02-08T09:33:26","modified_gmt":"2019-02-08T08:33:26","slug":"el-diablo-primera-parte","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/2019\/02\/08\/el-diablo-primera-parte\/","title":{"rendered":"EL DIABLO, PRIMERA PARTE"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/02\/Jan_Brueghel_-__Tentaciones_de_San_Antonio_Abad__-_Google_Art_Project-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2861\" src=\"\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/02\/Jan_Brueghel_-__Tentaciones_de_San_Antonio_Abad__-_Google_Art_Project-1-300x196.jpg\" alt=\"jan_brueghel_-__tentaciones_de_san_antonio_abad__-_google_art_project-1\" width=\"300\" height=\"196\" srcset=\"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/02\/Jan_Brueghel_-__Tentaciones_de_San_Antonio_Abad__-_Google_Art_Project-1-300x196.jpg 300w, https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/02\/Jan_Brueghel_-__Tentaciones_de_San_Antonio_Abad__-_Google_Art_Project-1-768x502.jpg 768w, https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/02\/Jan_Brueghel_-__Tentaciones_de_San_Antonio_Abad__-_Google_Art_Project-1-1024x670.jpg 1024w, https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/02\/Jan_Brueghel_-__Tentaciones_de_San_Antonio_Abad__-_Google_Art_Project-1.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Publicado en El Norte de Castilla el 8 de febrero de 2019<\/p>\n<p><span style=\"color: #0000ff; font-size: 14pt;\">El diablo, tal vez. Las mil caras del maligno. Una temporada en el infierno. Cualquier presentaci\u00f3n vale para sumergirnos en el fantasmag\u00f3rico universo de los Brueghel. Es el viaje que nos propone el Museo Nacional de Escultura a trav\u00e9s de una exposici\u00f3n vertebrada alrededor de un portentoso lienzo del pintor flamenco Jan Brueghel titulado \u201cLas tentaciones de San Antonio\u201d. Junto a \u00e9l, cuadros que siguen la estela de El Bosco imitando sus peculiares parajes devastados y cielos enrojecidos por pavorosos incendios. El demonio, la tentaci\u00f3n y el pecado protagonizando cuadros de car\u00e1cter fantasmal, repletos de alucinaciones diab\u00f3licas y en los que reina un ambiente de danza siniestra. Eso sin contar alguna curiosa obra como un relieve encargado a dos disc\u00edpulos de Berruguete para el Hospital de San Ant\u00f3n de Valladolid, regido por antoninos, orden dedicada a tratar el \u201cmal de los ardientes\u201d. Una segunda parte de la exposici\u00f3n est\u00e1 centrada en los grabados aleg\u00f3ricos de \u201cLos siete pecados capitales\u201d, de Pieter Breughel, y su fant\u00e1stica traves\u00eda al siglo XXI gracias a las ilustraciones animadas del belga Antoine Roegiers. Pero volvamos al principio. La beata Magdalena de San Jer\u00f3nimo fund\u00f3 en Valladolid, bajo protecci\u00f3n real y del concejo municipal, la primera c\u00e1rcel para mujeres de Espa\u00f1a. En realidad, Casa P\u00eda de Santa Mar\u00eda Magdalena o de la Aprobaci\u00f3n, conocida tambi\u00e9n como Casa de las Arrepentidas. Una \u201cgalera para mujeres\u201d o c\u00e1rcel correccional para castigo de las mujeres vagantes y ladronas, alcahuetas, hechiceras y otras semejantes. Para una de las capillas de la iglesia, la beata encarg\u00f3 a Jan Brueghel un cuadro muy especial que ayudara a las pecadoras a resistir las tentaciones. Un cuadro valorado en mil ducados y del que el mism\u00edsimo Pantoja de la Cruz lleg\u00f3 a hacer una copia. \u201cLas tentaciones de San Antonio\u201d expresa a la perfecci\u00f3n la resistencia del santo a los asaltos del maligno. El eremita entregado a sus oraciones mientras le acosan monstruos y seres mal\u00e9ficos. El eremita resistiendo las tentaciones carnales personificadas en mujeres convertidas en instrumentos del demonio. El eremita, en fin, ascendiendo al cielo y rodeado por una legi\u00f3n de demonios que intenta impedirlo. Pues eso. Exposici\u00f3n fastuosa y diab\u00f3lica. Un inquietante universo infernal. Y, por supuesto, el diablo protagonizando un mundo de carnaval.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado en El Norte de Castilla el 8 de febrero de 2019 El diablo, tal vez. Las mil caras del maligno. Una temporada en el infierno. Cualquier presentaci\u00f3n vale para sumergirnos en el fantasmag\u00f3rico universo de los Brueghel. Es el viaje que nos propone el Museo Nacional de Escultura a trav\u00e9s de una exposici\u00f3n vertebrada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2860","post","type-post","status-publish","format-standard","hentry","category-el-norte-de-castilla"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/2860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/comments?post=2860"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/2860\/revisions"}],"predecessor-version":[{"id":2863,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/2860\/revisions\/2863"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/media?parent=2860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/categories?post=2860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/tags?post=2860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}