{"id":2908,"date":"2019-04-05T09:18:31","date_gmt":"2019-04-05T08:18:31","guid":{"rendered":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/?p=2908"},"modified":"2019-04-05T09:18:31","modified_gmt":"2019-04-05T08:18:31","slug":"geometria-del-desprecio","status":"publish","type":"post","link":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/2019\/04\/05\/geometria-del-desprecio\/","title":{"rendered":"GEOMETR\u00cdA DEL DESPRECIO"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/04\/geometr\u00eda-del-desprecio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2909\" src=\"\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/04\/geometr\u00eda-del-desprecio-205x300.jpg\" alt=\"geometria-del-desprecio\" width=\"205\" height=\"300\" srcset=\"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/04\/geometr\u00eda-del-desprecio-205x300.jpg 205w, https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-content\/uploads\/sites\/3\/2019\/04\/geometr\u00eda-del-desprecio.jpg 453w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/a>Publicado en El Norte de Castilla el 5 de abril de 2019<\/p>\n<p><span style=\"font-size: 14pt; color: #0000ff;\">Auschwitz es el templo del horror. La conciencia que nos recuerda de manera constante e indefectible d\u00f3nde se coge el camino al infierno. Un trocito del averno que sigue oliendo a muerte, a hambre, a enfermedad, a tortura, a Zyklon B. All\u00ed fueron recluidas 1.300.000 personas. La mayor\u00eda murieron exterminadas. Hoy es patrimonio de la Humanidad de la Unesco y un museo memorial que visitan m\u00e1s de dos millones de personas al a\u00f1o. Hace un par de semanas los responsables del museo de Auschwitz publicaron el siguiente mensaje: \u201cCuando venga a Auschwitz recuerde que est\u00e1 en un lugar en el que fueron asesinadas m\u00e1s de un mill\u00f3n de personas. Respete su memoria. Hay lugares mejores para aprender a andar sobre una viga que un lugar que simboliza la deportaci\u00f3n de cientos de miles de personas\u201d. Cuatro fotos de cuatro croma\u00f1ones haciendo equilibrios sobre las v\u00edas f\u00e9rreas que transportaban a los detenidos directamente a las c\u00e1maras de gas ilustraban el comentario. El debate no se ha hecho esperar. Los expertos acusan a la generaci\u00f3n selfie de haber convertido Auschwitz en una Disneylandia para instagramers, un parque de atracciones atestado de adolescentes ignorantes m\u00e1s preocupados en hacerse su foto y subirla a las redes sociales que en reflexionar sobre la tragedia humana que tuvo lugar all\u00ed. El resultado: turistas graciosos y groseros posando delante de un crematorio, realizando gestos obscenos, haci\u00e9ndose selfies entre risas. Pero no todo es culpa de los adolescentes, ni esa falta de empat\u00eda tiene lugar solo en sitios como Auschwitz. Casi peor es ver c\u00f3mo los cretinos de turno no dejan de grabar con su m\u00f3vil a gente que ha tenido un accidente y lloran en el suelo su pena. Lo vemos casi todos los d\u00edas. En la pasada Volta a Catalu\u00f1a un mermado estaba con su m\u00f3vil grabando al pelot\u00f3n en un descenso cuando un corredor perdi\u00f3 el control de su bici. En ese momento ya se le escucha re\u00edrse con ganas. Al verle en el suelo, incluso se mofa y comenta \u201cahora le robo la bici\u201d, y mientras el ciclista grita de dolor, se acerca a \u00e9l y sigue grabando en primer plano su sufrimiento. Por si fuera poco, este saco de mierda, lejos de arrepentirse, declara con posterioridad que solo lamenta haber confiado en sus amigos (al enviarles el video) acusando adem\u00e1s al ciclista de bajar por donde no ten\u00eda que bajar. Estamos perdidos. La geometr\u00eda del desprecio ya reina m\u00f3vil en mano.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicado en El Norte de Castilla el 5 de abril de 2019 Auschwitz es el templo del horror. La conciencia que nos recuerda de manera constante e indefectible d\u00f3nde se coge el camino al infierno. Un trocito del averno que sigue oliendo a muerte, a hambre, a enfermedad, a tortura, a Zyklon B. All\u00ed fueron [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2908","post","type-post","status-publish","format-standard","hentry","category-el-norte-de-castilla"],"_links":{"self":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/2908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/comments?post=2908"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/2908\/revisions"}],"predecessor-version":[{"id":2910,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/posts\/2908\/revisions\/2910"}],"wp:attachment":[{"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/media?parent=2908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/categories?post=2908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elnortedecastilla.es\/vicentealvarez\/wp-json\/wp\/v2\/tags?post=2908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}